{"id":52180,"date":"2019-10-04T10:48:15","date_gmt":"2019-10-04T08:48:15","guid":{"rendered":"https:\/\/ppdegalicia.com\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/"},"modified":"2019-10-04T10:48:15","modified_gmt":"2019-10-04T08:48:15","slug":"o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes","status":"publish","type":"post","link":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/","title":{"rendered":"O PPdeG reitera a esixencia para que o Goberno central rectifique e incorpore a lingua galega no Certame Arqu\u00edmedes"},"content":{"rendered":"<p>&nbsp;A deputada do Grupo Popular Sandra V\u00e1zquez reiterou hoxe no Parlamento a esixencia para que o Goberno central rectifique a s\u00faa decisi\u00f3n de incorporar \u00e1 lingua galega, as\u00ed como calquera outra lingua oficial espa\u00f1ola, no Certame Arqu\u00edmedes, \u201csum\u00e1ndonos \u00e1 solicitude que xa fixo o Goberno galego \u00e1 secretaria de Estado de Universidades, Investigaci\u00f3n, Desarrollo e Innovaci\u00f3n hai un mes\u201d.<\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>Sandra V\u00e1zquez sinalou que a decisi\u00f3n do Goberno central de exclu\u00edr a lingua galega no Certame Arqu\u00edmedes \u201c\u00e9 unha forma de deixar f\u00f3ra unha parte do talento cient\u00edfico producido en Galicia\u201d. \u201cPor enriba da calidade e o interese dos traballos excl\u00fae linguas tan v\u00e1lidas como calquera outra na investigaci\u00f3n\u201d sinalou.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEsta decisi\u00f3n do Goberno socialista contrad\u00ed moita normativa, entre a que destaca a Carta Europea de Linguas Rexionais e Minorizadas, ratificada polo Estado espa\u00f1ol en 2001\u201d, sinalou. Ademais, lembrou que \u201ca Constituci\u00f3n establece o pluriling\u00fcismo oficial e o car\u00e1cter oficial doutras linguas espa\u00f1olas, as\u00ed como a riqueza das distintas modalidades ling\u00fc\u00edsticas de Espa\u00f1a, como patrimonio cultural, obxecto de respecto e protecci\u00f3n\u201d, apuntou.<\/p>\n<p>&nbsp;<\/p>\n<p>A deputada popular subli\u00f1ou que a Xunta \u201cest\u00e1 comprometida coa promoci\u00f3n e investigaci\u00f3n da lingua galega po\u00f1endo medios e, sobre todo, orzamento<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;A deputada do Grupo Popular Sandra V\u00e1zquez reiterou hoxe no Parlamento a esixencia para que o Goberno central rectifique a s\u00faa decisi\u00f3n de incorporar \u00e1 lingua galega, as\u00ed como calquera outra lingua oficial espa\u00f1ola, no Certame Arqu\u00edmedes, \u201csum\u00e1ndonos \u00e1 solicitude que xa fixo o Goberno galego \u00e1 secretaria de Estado de Universidades, Investigaci\u00f3n, Desarrollo e [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52180","post","type-post","status-publish","format-standard","hentry","category-pp-de-galicia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O PPdeG reitera a esixencia para que o Goberno central rectifique e incorpore a lingua galega no Certame Arqu\u00edmedes - PP de Galicia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O PPdeG reitera a esixencia para que o Goberno central rectifique e incorpore a lingua galega no Certame Arqu\u00edmedes - PP de Galicia\" \/>\n<meta property=\"og:description\" content=\"&nbsp;A deputada do Grupo Popular Sandra V\u00e1zquez reiterou hoxe no Parlamento a esixencia para que o Goberno central rectifique a s\u00faa decisi\u00f3n de incorporar \u00e1 lingua galega, as\u00ed como calquera outra lingua oficial espa\u00f1ola, no Certame Arqu\u00edmedes, \u201csum\u00e1ndonos \u00e1 solicitude que xa fixo o Goberno galego \u00e1 secretaria de Estado de Universidades, Investigaci\u00f3n, Desarrollo e [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/\" \/>\n<meta property=\"og:site_name\" content=\"PP de Galicia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/ppdegalicia\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-10-04T08:48:15+00:00\" \/>\n<meta name=\"author\" content=\"Super User\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:site\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Super User\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\\\/\"},\"author\":{\"name\":\"Super User\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/d0f013b8388c980665d44009ab762960\"},\"headline\":\"O PPdeG reitera a esixencia para que o Goberno central rectifique e incorpore a lingua galega no Certame Arqu\u00edmedes\",\"datePublished\":\"2019-10-04T08:48:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\\\/\"},\"wordCount\":242,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"articleSection\":[\"PP de Galicia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\\\/\",\"name\":\"O PPdeG reitera a esixencia para que o Goberno central rectifique e incorpore a lingua galega no Certame Arqu\u00edmedes - PP de Galicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\"},\"datePublished\":\"2019-10-04T08:48:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O PPdeG reitera a esixencia para que o Goberno central rectifique e incorpore a lingua galega no Certame Arqu\u00edmedes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"name\":\"Partido Popular de Galicia\",\"description\":\"Partido Popular de Galicia\",\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"alternateName\":\"PP de Galicia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\",\"name\":\"Partido Popular de Galicia\",\"alternateName\":\"PP de Galicia\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"contentUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"width\":512,\"height\":512,\"caption\":\"Partido Popular de Galicia\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ppdegalicia\\\/\",\"https:\\\/\\\/x.com\\\/ppdegalicia\",\"https:\\\/\\\/www.tiktok.com\\\/@ppdegalicia\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ppdegalicia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/d0f013b8388c980665d44009ab762960\",\"name\":\"Super User\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"caption\":\"Super User\"},\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/author\\\/ppdegaliciagestion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O PPdeG reitera a esixencia para que o Goberno central rectifique e incorpore a lingua galega no Certame Arqu\u00edmedes - PP de Galicia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/","og_locale":"es_ES","og_type":"article","og_title":"O PPdeG reitera a esixencia para que o Goberno central rectifique e incorpore a lingua galega no Certame Arqu\u00edmedes - PP de Galicia","og_description":"&nbsp;A deputada do Grupo Popular Sandra V\u00e1zquez reiterou hoxe no Parlamento a esixencia para que o Goberno central rectifique a s\u00faa decisi\u00f3n de incorporar \u00e1 lingua galega, as\u00ed como calquera outra lingua oficial espa\u00f1ola, no Certame Arqu\u00edmedes, \u201csum\u00e1ndonos \u00e1 solicitude que xa fixo o Goberno galego \u00e1 secretaria de Estado de Universidades, Investigaci\u00f3n, Desarrollo e [&hellip;]","og_url":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/","og_site_name":"PP de Galicia","article_publisher":"https:\/\/www.instagram.com\/ppdegalicia\/","article_published_time":"2019-10-04T08:48:15+00:00","author":"Super User","twitter_card":"summary_large_image","twitter_creator":"@ppdegalicia","twitter_site":"@ppdegalicia","twitter_misc":{"Escrito por":"Super User","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/#article","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/"},"author":{"name":"Super User","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/d0f013b8388c980665d44009ab762960"},"headline":"O PPdeG reitera a esixencia para que o Goberno central rectifique e incorpore a lingua galega no Certame Arqu\u00edmedes","datePublished":"2019-10-04T08:48:15+00:00","mainEntityOfPage":{"@id":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/"},"wordCount":242,"commentCount":0,"publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"articleSection":["PP de Galicia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/","url":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/","name":"O PPdeG reitera a esixencia para que o Goberno central rectifique e incorpore a lingua galega no Certame Arqu\u00edmedes - PP de Galicia","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/#website"},"datePublished":"2019-10-04T08:48:15+00:00","breadcrumb":{"@id":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-reitera-a-esixencia-para-que-o-goberno-central-rectifique-e-incorpore-a-lingua-galega-no-certame-arquimedes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ppdegalicia.com\/es\/"},{"@type":"ListItem","position":2,"name":"O PPdeG reitera a esixencia para que o Goberno central rectifique e incorpore a lingua galega no Certame Arqu\u00edmedes"}]},{"@type":"WebSite","@id":"https:\/\/ppdegalicia.com\/es\/#website","url":"https:\/\/ppdegalicia.com\/es\/","name":"Partido Popular de Galicia","description":"Partido Popular de Galicia","publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"alternateName":"PP de Galicia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ppdegalicia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ppdegalicia.com\/es\/#organization","name":"Partido Popular de Galicia","alternateName":"PP de Galicia","url":"https:\/\/ppdegalicia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","contentUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","width":512,"height":512,"caption":"Partido Popular de Galicia"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ppdegalicia\/","https:\/\/x.com\/ppdegalicia","https:\/\/www.tiktok.com\/@ppdegalicia","https:\/\/www.youtube.com\/user\/ppdegalicia"]},{"@type":"Person","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/d0f013b8388c980665d44009ab762960","name":"Super User","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","caption":"Super User"},"url":"https:\/\/ppdegalicia.com\/es\/author\/ppdegaliciagestion\/"}]}},"_links":{"self":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/52180","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/comments?post=52180"}],"version-history":[{"count":0,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/52180\/revisions"}],"wp:attachment":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/media?parent=52180"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/categories?post=52180"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/tags?post=52180"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}