{"id":52467,"date":"2019-07-15T08:17:16","date_gmt":"2019-07-15T06:17:16","guid":{"rendered":"https:\/\/ppdegalicia.com\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/"},"modified":"2019-07-15T08:17:16","modified_gmt":"2019-07-15T06:17:16","slug":"puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia","status":"publish","type":"post","link":"https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/","title":{"rendered":"Puy incide que \u201cexisten mecanismos\u201d para que o Goberno central abone os 700 mill\u00f3ns que debe a Galicia"},"content":{"rendered":"<p>Santiago, 15 de xullo de 2019.- O portavoz do Grupo Popular, Pedro Puy, incidiu hoxe que \u201cexisten mecanismos legais para que o Goberno central abone os 700 mill\u00f3ns de euros que lle debe a Galicia, logo de que no Consejo de Ministros da semana pasada autorizara a compra de blindados para o Ex\u00e9rcito espa\u00f1ol por importe de 2.300 mill\u00f3ns de euros.<\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>As\u00ed mesmo, Puy amosou a satisfacci\u00f3n porque o Goberno do Estado optara por utilizar os instrumentos do Estado de Dereito, como aconsellaba o informe da Comisi\u00f3n de Expertos designada pola Xunta a proposta do Parlamento galego, para conseguir reintegrar ao patrimonio p\u00fablico o Pazo de Meir\u00e1s.<\/p>\n<p>&nbsp;<\/p>\n<p>Puy iniciou a s\u00faa comparecencia ante os medios facendo unha referencia \u00e1 actividade parlamentaria que se vai desenvolver esta semana, centrada no traballo da ponencia do proxecto de Lei de Patrimonio Natural. Neste sentido, avanzou a posibilidade de que esta mesma semana se celebre unha sesi\u00f3n da Comisi\u00f3n 2\u00aa do Parlamento galego para debater e aprobar o ditame deste texto lexislativo, co que quedar\u00eda preparado para a s\u00faa aprobaci\u00f3n definitiva no primeiro Pleno que se celebre.<\/p>\n<p>&nbsp;<\/p>\n<p>Pedro Puy insistiu que \u201co principal problema que ten a curto prazo a Comunidade galega \u00e9 a falta de transferencia de 530 mill\u00f3ns desde o Goberno do Estado, correspondentes \u00e1s entregas \u00e1 conta de 2019 e a unha mensualidade do IVE de 2017, aos que se suman outros 170 mill\u00f3ns dos incentivos por cumprir todos os par\u00e1metros de estabilidade orzamentaria en 2017 e 2018\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Na s\u00faa intervenci\u00f3n, o portavoz popular insistiu que \u201cexisten mecanismos legais que permiten ao Goberno de Pedro S\u00e1nchez facer estas transferencias, como \u00e9 a aprobaci\u00f3n dun decreto-lei por raz\u00f3ns de urxencia que ser\u00eda convalidable polo Congreso no&nbsp; prazo de un mes\u201d. \u201cEstamos a falar dun problema que afecta a varias comunidades aut\u00f3nomas, polo que seguramente non haber\u00eda problema para a convalidaci\u00f3n deste decreto-lei polo Congreso\u201d, engadiu.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>RAZ\u00d3NS DE URXENCIA E INTERESE XERAL<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Puy referiuse ao acordo adoptado no \u00faltimo Consejo de Ministros a trav\u00e9s do que se autoriza ao Ministerio de Defensa a asinar un contrato para a adquisici\u00f3n de blindados por un importe de 2.100 mill\u00f3ns de euros. \u201cO Goberno central en funci\u00f3ns xustifica esta decisi\u00f3n por raz\u00f3ns de urxencia e de interese xeral, polo que \u00e9 dif\u00edcil entender cal \u00e9 a diferencia en relaci\u00f3n coas entregas a conta que ten que dar o Estado \u00e1s comunidades aut\u00f3nomas\u201d, dixo.<\/p>\n<p>&nbsp;<\/p>\n<p>Do mesmo xeito que no caso dos blindados, tanto nas entregas a conta como da devoluci\u00f3n do IVE \u201cexiste un compromiso anterior por parte do Goberno do Estado, que se pode considerar de urxente necesidade para o mantemento da sanidade, a educaci\u00f3n e os servizos socias que prestan as comunidades aut\u00f3nomas, que inclu\u00edron estes importes nos seus orzamentos para prestar estes servizos\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>O portavoz popular avanzou que \u201ccontinuaremos demandando o que por xustiza lle corresponde a Galicia\u201d e lamentou que a Xunta \u201cxa tivo que aprobar operaci\u00f3ns de endebedamento para cubrir estas faltas de transferencias do Estado\u201d. Neste sentido, avogou porque \u201ctodas as forzas pol\u00edticas estiveramos de acordo nesta demanda\u201d porque se trata de pensar en Galicia, nos servizos que reciben os cidad\u00e1ns e no pago aos provedores da comunidade\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Na s\u00faa comparecencia, Puy tam\u00e9n se referiu \u00e1 decisi\u00f3n do Goberno central de presentar unha demanda no Xulgado de A Coru\u00f1a para a reintegraci\u00f3n ao patrimonio p\u00fablico do Pazo de Meir\u00e1s. Neste sentido, salientou que \u201ca argumentaci\u00f3n xur\u00eddica desta demanda basicamente se axusta aos criterios xur\u00eddicos que propuxo a Comisi\u00f3n de Expertos que se creou, a proposta do Grupo Popular neste Parlamento e que non foi apoiada polos demais grupos, a\u00ednda que despois si se conseguiu unanimidade para trasladar ao Estado o ditame desa Comisi\u00f3n\u201d. Neste sentido, lembrou que nese ditame tam\u00e9n se demandaba que a Xunta se presentase como coadiuvante a esa demanda do Estado, decisi\u00f3n que, logo de consultar aos servizos xur\u00eddicos, xa ten previsto realizar o Goberno galego.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201c\u00c9 un motivo de satisfacci\u00f3n que se utilicen os instrumentos do Estado de Dereito, polo que agora est\u00e1 en mans da Xustiza a soluci\u00f3n a este asunto e confiamos que esa demanda permita ganar para o p\u00fablico o que foi durante tantos anos a residencia do xefe do Estado e non dun veraneante particular\u201d, apuntou.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>PROBLEMAS INTERNOS<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Por \u00faltimo, respecto da toma do nomeamento de Corina Porro como delegada da Xunta en Vigo, Pedro Puy asegurou que \u201cten capacidades para exercer esta labor que se lle encomenda, porque cumpre sobradamente pola s\u00faa experiencia na administraci\u00f3n e polo co\u00f1ecemento do territorio\u201d. \u201cEstamos ante unha decisi\u00f3n do Goberno galego adecuada \u00e1 normativa, pero ademais \u00e9&nbsp; dif\u00edcil pensar nalgu\u00e9n mellor que Corina Porro para exercer as competencias da Xunta en Vigo, que foi alcaldesa desa cidade e ten un car\u00e1cter persoal que lle vai permitir avanzar na cooperaci\u00f3n con todas as administraci\u00f3ns\u201d, engadiu.<\/p>\n<p>&nbsp;<\/p>\n<p>Puy considerou \u201csorprendente que nos digan que unha persoa de confianza do Goberno ocupa unha delegaci\u00f3n\u201d, ante o que dixo que \u201cnon \u00e9 a primeira vez que alg\u00fan grupo parlamentario intenta traer \u00e1 C\u00e1mara problemas internos propios, neste caso sobre os nomeamentos da Administraci\u00f3n Xeral do Estado, para que sexamos os demais os que os aireemos\u201d. As\u00ed, apuntou que \u201cse os socialistas entenden que este \u00e9 o motivo para a celebraci\u00f3n dunha reuni\u00f3n da Deputaci\u00f3n Permanente, \u00e9 a mellor demostraci\u00f3n de que o pa\u00eds vai moi ben e moito mellor do que eles din\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santiago, 15 de xullo de 2019.- O portavoz do Grupo Popular, Pedro Puy, incidiu hoxe que \u201cexisten mecanismos legais para que o Goberno central abone os 700 mill\u00f3ns de euros que lle debe a Galicia, logo de que no Consejo de Ministros da semana pasada autorizara a compra de blindados para o Ex\u00e9rcito espa\u00f1ol por [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52467","post","type-post","status-publish","format-standard","hentry","category-pp-de-galicia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Puy incide que \u201cexisten mecanismos\u201d para que o Goberno central abone os 700 mill\u00f3ns que debe a Galicia - PP de Galicia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puy incide que \u201cexisten mecanismos\u201d para que o Goberno central abone os 700 mill\u00f3ns que debe a Galicia - PP de Galicia\" \/>\n<meta property=\"og:description\" content=\"Santiago, 15 de xullo de 2019.- O portavoz do Grupo Popular, Pedro Puy, incidiu hoxe que \u201cexisten mecanismos legais para que o Goberno central abone os 700 mill\u00f3ns de euros que lle debe a Galicia, logo de que no Consejo de Ministros da semana pasada autorizara a compra de blindados para o Ex\u00e9rcito espa\u00f1ol por [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/\" \/>\n<meta property=\"og:site_name\" content=\"PP de Galicia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/ppdegalicia\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-07-15T06:17:16+00:00\" \/>\n<meta name=\"author\" content=\"Super User\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:site\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Super User\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\\\/\"},\"author\":{\"name\":\"Super User\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/d0f013b8388c980665d44009ab762960\"},\"headline\":\"Puy incide que \u201cexisten mecanismos\u201d para que o Goberno central abone os 700 mill\u00f3ns que debe a Galicia\",\"datePublished\":\"2019-07-15T06:17:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\\\/\"},\"wordCount\":981,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"articleSection\":[\"PP de Galicia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\\\/\",\"name\":\"Puy incide que \u201cexisten mecanismos\u201d para que o Goberno central abone os 700 mill\u00f3ns que debe a Galicia - PP de Galicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\"},\"datePublished\":\"2019-07-15T06:17:16+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puy incide que \u201cexisten mecanismos\u201d para que o Goberno central abone os 700 mill\u00f3ns que debe a Galicia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"name\":\"Partido Popular de Galicia\",\"description\":\"Partido Popular de Galicia\",\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"alternateName\":\"PP de Galicia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\",\"name\":\"Partido Popular de Galicia\",\"alternateName\":\"PP de Galicia\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"contentUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"width\":512,\"height\":512,\"caption\":\"Partido Popular de Galicia\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ppdegalicia\\\/\",\"https:\\\/\\\/x.com\\\/ppdegalicia\",\"https:\\\/\\\/www.tiktok.com\\\/@ppdegalicia\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ppdegalicia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/d0f013b8388c980665d44009ab762960\",\"name\":\"Super User\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"caption\":\"Super User\"},\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/author\\\/ppdegaliciagestion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puy incide que \u201cexisten mecanismos\u201d para que o Goberno central abone os 700 mill\u00f3ns que debe a Galicia - PP de Galicia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/","og_locale":"es_ES","og_type":"article","og_title":"Puy incide que \u201cexisten mecanismos\u201d para que o Goberno central abone os 700 mill\u00f3ns que debe a Galicia - PP de Galicia","og_description":"Santiago, 15 de xullo de 2019.- O portavoz do Grupo Popular, Pedro Puy, incidiu hoxe que \u201cexisten mecanismos legais para que o Goberno central abone os 700 mill\u00f3ns de euros que lle debe a Galicia, logo de que no Consejo de Ministros da semana pasada autorizara a compra de blindados para o Ex\u00e9rcito espa\u00f1ol por [&hellip;]","og_url":"https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/","og_site_name":"PP de Galicia","article_publisher":"https:\/\/www.instagram.com\/ppdegalicia\/","article_published_time":"2019-07-15T06:17:16+00:00","author":"Super User","twitter_card":"summary_large_image","twitter_creator":"@ppdegalicia","twitter_site":"@ppdegalicia","twitter_misc":{"Escrito por":"Super User","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/#article","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/"},"author":{"name":"Super User","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/d0f013b8388c980665d44009ab762960"},"headline":"Puy incide que \u201cexisten mecanismos\u201d para que o Goberno central abone os 700 mill\u00f3ns que debe a Galicia","datePublished":"2019-07-15T06:17:16+00:00","mainEntityOfPage":{"@id":"https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/"},"wordCount":981,"commentCount":0,"publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"articleSection":["PP de Galicia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/","url":"https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/","name":"Puy incide que \u201cexisten mecanismos\u201d para que o Goberno central abone os 700 mill\u00f3ns que debe a Galicia - PP de Galicia","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/#website"},"datePublished":"2019-07-15T06:17:16+00:00","breadcrumb":{"@id":"https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ppdegalicia.com\/es\/puy-incide-que-existen-mecanismos-para-que-o-goberno-central-abone-os-700-millons-que-debe-a-galicia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ppdegalicia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Puy incide que \u201cexisten mecanismos\u201d para que o Goberno central abone os 700 mill\u00f3ns que debe a Galicia"}]},{"@type":"WebSite","@id":"https:\/\/ppdegalicia.com\/es\/#website","url":"https:\/\/ppdegalicia.com\/es\/","name":"Partido Popular de Galicia","description":"Partido Popular de Galicia","publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"alternateName":"PP de Galicia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ppdegalicia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ppdegalicia.com\/es\/#organization","name":"Partido Popular de Galicia","alternateName":"PP de Galicia","url":"https:\/\/ppdegalicia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","contentUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","width":512,"height":512,"caption":"Partido Popular de Galicia"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ppdegalicia\/","https:\/\/x.com\/ppdegalicia","https:\/\/www.tiktok.com\/@ppdegalicia","https:\/\/www.youtube.com\/user\/ppdegalicia"]},{"@type":"Person","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/d0f013b8388c980665d44009ab762960","name":"Super User","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","caption":"Super User"},"url":"https:\/\/ppdegalicia.com\/es\/author\/ppdegaliciagestion\/"}]}},"_links":{"self":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/52467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/comments?post=52467"}],"version-history":[{"count":0,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/52467\/revisions"}],"wp:attachment":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/media?parent=52467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/categories?post=52467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/tags?post=52467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}