{"id":52536,"date":"2019-02-18T16:22:37","date_gmt":"2019-02-18T14:22:37","guid":{"rendered":"https:\/\/ppdegalicia.com\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/"},"modified":"2019-02-18T16:22:37","modified_gmt":"2019-02-18T14:22:37","slug":"puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia","status":"publish","type":"post","link":"https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/","title":{"rendered":"Puy afirma que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais, deixando pendentes temas importantes en relaci\u00f3n con Galicia\u201d"},"content":{"rendered":"<div>Santiago, 18 de febreiro de 2019.- O portavoz do Grupo Popular, Pedro Puy, afirmou hoxe que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais\u201d, ademais de que o propio Goberno do Estado reco\u00f1ecera que exist\u00eda un desfase de m\u00e1is de 8.200 mill\u00f3ns de euros no proxecto de orzamentos.<br \/>\n<!--more-->\n<\/div>\n<div>&nbsp;<\/div>\n<div>As\u00ed mesmo, apuntou que \u201cquedan pendentes varios temas en relaci\u00f3n con Galicia, como a autorizaci\u00f3n para o gasto dos 125 mill\u00f3ns de euros do super\u00e1vit da Xunta; a resoluci\u00f3n do problema do IVE que reciben as autonom\u00edas, que no caso de Galicia ronda os 200 mill\u00f3ns de euros; a transferencia da AP-9; a soluci\u00f3n \u00e1s empresas electrointensivas, como Alcoa; a construci\u00f3n das fragatas F-110 en Ferrol; ou a reivindicaci\u00f3n da propiedade do Pazo de Meir\u00e1s.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<p>&nbsp;<\/p>\n<div>Ao remate da reuni\u00f3n do Grupo Popular celebrada esta ma\u00f1\u00e1, Pedro Puy informou que no vindeiro Pleno \u201cestar\u00e1 en disposici\u00f3n de inclu\u00edrse o debate de totalidade do proxecto de Lei de rehabilitaci\u00f3n e de rexeneraci\u00f3n e renovaci\u00f3n urbana de Galicia\u201d. Segundo explicou, esta nova norma c\u00e9ntrase \u201cna rehabilitaci\u00f3n e na recuperaci\u00f3n de edificios que te\u00f1en un valor patrimonial e urbano importante nos cascos urbanos de Galicia ou nos Cami\u00f1os de Santiago como factor de dinamizaci\u00f3n econ\u00f3mica e social\u201d, ao tempo que permite axilizar a tramitaci\u00f3n de licenzas para actuar nos inmobles, porque non ser\u00e1 necesario o informe de Patrimonio cando non se trate dun ben de interese cultural; e incorpora sanci\u00f3ns para previr e loitar contra as pintadas en edificaci\u00f3ns hist\u00f3ricas ou de \u00e1mbitos protexidos.<\/div>\n<div>&nbsp;<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div><strong>INCERTEZAS NO \u00c1MBITO ECON\u00d3MICO<\/strong><\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<p>&nbsp;<\/p>\n<div>Respecto do adianto das elecci\u00f3ns xerais, Puy indicou que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds nun per\u00edodo tan corto de tempo a d\u00faas campa\u00f1as electorais\u201d. Ademais, subli\u00f1ou que \u201cabre unha serie de incertezas con car\u00e1cter xeral no \u00e1mbito econ\u00f3mico\u201d, logo de que se demostrara que no proxecto de orzamentos \u201cos ingresos estaban inflados en relaci\u00f3ns coa previsi\u00f3n de gastos\u201d.<\/div>\n<div>&nbsp;<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div>O portavoz popular criticou que \u201ca propia ministra de Facenda reco\u00f1eceu un desfase de m\u00e1is de 8.200 mill\u00f3ns de euros nas contas xerais, coincidindo con organismos que criticaron os orzamentos, como o Banco de Espa\u00f1a, a Comisi\u00f3n Europea ou a AIReF\u201d, resultado das \u201cdecisi\u00f3ns do Goberno central adoptadas por decreto que van facer que o d\u00e9ficit p\u00fablico suba ata o 2,4 por cento\u201d.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<p>&nbsp;<\/p>\n<div>Diante desta situaci\u00f3n, Pedro Puy afirmou que \u201cvai haber que facer axustes e nos tememos que vaian polo lado dos investimentos\u201d. Deste xeito, e logo de que o Goberno socialista xa avanzara un axuste dos investimentos para Galicia no proxecto de orzamentos, \u201ccorremos serio risco de que o ano que ven a econom\u00eda galega deixe de ter o impulso que lle da o investimento p\u00fablico por parte do Estado\u201d.<\/div>\n<div>&nbsp;<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div><strong>TEMAS PENDENTES<\/strong><\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<p>&nbsp;<\/p>\n<div>Puy indicou que \u201cquedan temas pendentes con Galicia que nos preocupan\u201d. En primeiro lugar, referiuse \u00e1 autorizaci\u00f3n para o gasto dos 125 mill\u00f3ns de euros do super\u00e1vit da Xunta do pasado ano, porque \u201co contrario ser\u00eda que se primara \u00e1s comunidades incumpridoras, fronte a aquelas que como Galicia que compren a regra de gasto e te\u00f1en super\u00e1vit\u201d.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<p>&nbsp;<\/p>\n<div>En segundo lugar, o portavoz popular concretou que \u201cqueda pendente e confiamos que se resolva o tema do ingreso da mensualidade pendente do IVE \u00e1s comunidades aut\u00f3nomas\u201d, que no caso de Galicia sup\u00f3n arredor 200 mill\u00f3ns de euros.<\/div>\n<div>&nbsp;<\/div>\n<div>&nbsp;<\/div>\n<p>Entre os asuntos pendentes por parte do Goberno central, Pedro Puy citou a transferencia da AP-9; a soluci\u00f3n \u00e1s empresas electrointensivas, nomeadamente Alcoa; que se asinen os contratos para a construci\u00f3n das fragatas F-110 nos estaleiros de Ferrol; e tam\u00e9n \u201cser\u00eda bo que se soubese algo sobre a devoluci\u00f3n do Pazo de Meir\u00e1s\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santiago, 18 de febreiro de 2019.- O portavoz do Grupo Popular, Pedro Puy, afirmou hoxe que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais\u201d, ademais de que o propio Goberno do Estado reco\u00f1ecera que exist\u00eda un desfase de m\u00e1is de 8.200 mill\u00f3ns de euros no [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52536","post","type-post","status-publish","format-standard","hentry","category-pp-de-galicia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Puy afirma que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais, deixando pendentes temas importantes en relaci\u00f3n con Galicia\u201d - PP de Galicia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puy afirma que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais, deixando pendentes temas importantes en relaci\u00f3n con Galicia\u201d - PP de Galicia\" \/>\n<meta property=\"og:description\" content=\"Santiago, 18 de febreiro de 2019.- O portavoz do Grupo Popular, Pedro Puy, afirmou hoxe que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais\u201d, ademais de que o propio Goberno do Estado reco\u00f1ecera que exist\u00eda un desfase de m\u00e1is de 8.200 mill\u00f3ns de euros no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/\" \/>\n<meta property=\"og:site_name\" content=\"PP de Galicia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/ppdegalicia\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-18T14:22:37+00:00\" \/>\n<meta name=\"author\" content=\"Super User\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:site\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Super User\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\\\/\"},\"author\":{\"name\":\"Super User\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/d0f013b8388c980665d44009ab762960\"},\"headline\":\"Puy afirma que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais, deixando pendentes temas importantes en relaci\u00f3n con Galicia\u201d\",\"datePublished\":\"2019-02-18T14:22:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\\\/\"},\"wordCount\":733,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"articleSection\":[\"PP de Galicia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\\\/\",\"name\":\"Puy afirma que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais, deixando pendentes temas importantes en relaci\u00f3n con Galicia\u201d - PP de Galicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\"},\"datePublished\":\"2019-02-18T14:22:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puy afirma que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais, deixando pendentes temas importantes en relaci\u00f3n con Galicia\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"name\":\"Partido Popular de Galicia\",\"description\":\"Partido Popular de Galicia\",\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"alternateName\":\"PP de Galicia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\",\"name\":\"Partido Popular de Galicia\",\"alternateName\":\"PP de Galicia\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"contentUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"width\":512,\"height\":512,\"caption\":\"Partido Popular de Galicia\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ppdegalicia\\\/\",\"https:\\\/\\\/x.com\\\/ppdegalicia\",\"https:\\\/\\\/www.tiktok.com\\\/@ppdegalicia\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ppdegalicia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/d0f013b8388c980665d44009ab762960\",\"name\":\"Super User\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"caption\":\"Super User\"},\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/author\\\/ppdegaliciagestion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Puy afirma que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais, deixando pendentes temas importantes en relaci\u00f3n con Galicia\u201d - PP de Galicia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/","og_locale":"es_ES","og_type":"article","og_title":"Puy afirma que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais, deixando pendentes temas importantes en relaci\u00f3n con Galicia\u201d - PP de Galicia","og_description":"Santiago, 18 de febreiro de 2019.- O portavoz do Grupo Popular, Pedro Puy, afirmou hoxe que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais\u201d, ademais de que o propio Goberno do Estado reco\u00f1ecera que exist\u00eda un desfase de m\u00e1is de 8.200 mill\u00f3ns de euros no [&hellip;]","og_url":"https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/","og_site_name":"PP de Galicia","article_publisher":"https:\/\/www.instagram.com\/ppdegalicia\/","article_published_time":"2019-02-18T14:22:37+00:00","author":"Super User","twitter_card":"summary_large_image","twitter_creator":"@ppdegalicia","twitter_site":"@ppdegalicia","twitter_misc":{"Escrito por":"Super User","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/#article","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/"},"author":{"name":"Super User","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/d0f013b8388c980665d44009ab762960"},"headline":"Puy afirma que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais, deixando pendentes temas importantes en relaci\u00f3n con Galicia\u201d","datePublished":"2019-02-18T14:22:37+00:00","mainEntityOfPage":{"@id":"https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/"},"wordCount":733,"commentCount":0,"publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"articleSection":["PP de Galicia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/","url":"https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/","name":"Puy afirma que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais, deixando pendentes temas importantes en relaci\u00f3n con Galicia\u201d - PP de Galicia","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/#website"},"datePublished":"2019-02-18T14:22:37+00:00","breadcrumb":{"@id":"https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ppdegalicia.com\/es\/puy-afirma-que-non-parece-o-mais-razoable-someter-ao-pais-nun-periodo-tan-corto-de-tempo-a-duas-campanas-electorais-deixando-pendentes-temas-importantes-en-relacion-con-galicia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ppdegalicia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Puy afirma que \u201cnon parece o m\u00e1is razoable someter ao pa\u00eds, nun per\u00edodo tan corto de tempo, a d\u00faas campa\u00f1as electorais, deixando pendentes temas importantes en relaci\u00f3n con Galicia\u201d"}]},{"@type":"WebSite","@id":"https:\/\/ppdegalicia.com\/es\/#website","url":"https:\/\/ppdegalicia.com\/es\/","name":"Partido Popular de Galicia","description":"Partido Popular de Galicia","publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"alternateName":"PP de Galicia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ppdegalicia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ppdegalicia.com\/es\/#organization","name":"Partido Popular de Galicia","alternateName":"PP de Galicia","url":"https:\/\/ppdegalicia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","contentUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","width":512,"height":512,"caption":"Partido Popular de Galicia"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ppdegalicia\/","https:\/\/x.com\/ppdegalicia","https:\/\/www.tiktok.com\/@ppdegalicia","https:\/\/www.youtube.com\/user\/ppdegalicia"]},{"@type":"Person","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/d0f013b8388c980665d44009ab762960","name":"Super User","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","caption":"Super User"},"url":"https:\/\/ppdegalicia.com\/es\/author\/ppdegaliciagestion\/"}]}},"_links":{"self":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/52536","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/comments?post=52536"}],"version-history":[{"count":0,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/52536\/revisions"}],"wp:attachment":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/media?parent=52536"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/categories?post=52536"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/tags?post=52536"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}