{"id":52747,"date":"2018-04-27T16:58:01","date_gmt":"2018-04-27T14:58:01","guid":{"rendered":"https:\/\/ppdegalicia.com\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/"},"modified":"2018-04-27T16:58:01","modified_gmt":"2018-04-27T14:58:01","slug":"jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega","status":"publish","type":"post","link":"https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/","title":{"rendered":"Jos\u00e9 Gonz\u00e1lez asegura que \u201ctemos todos os medios para facer un ditame na Comisi\u00f3n sobre a pol\u00edtica forestal \u00e1 altura do que nos demanda a sociedade galega\u201d"},"content":{"rendered":"<p><strong>Santiago, 27 de abril de 2018.-<\/strong> O portavoz do Medio Rural, Jos\u00e9 Gonz\u00e1lez, afirmou hoxe, logo da constituci\u00f3n da ponencia encargada de elaborar o ditame da Comisi\u00f3n de estudo das reformas da pol\u00edtica forestal e de prevenci\u00f3n e extinci\u00f3n de incendios, que \u201ctemos todos os medios para poder facer un ditame \u00e1 altura do que nos demanda a sociedade galega\u201d. \u201cEspera un traballo duro porque o compromiso \u00e9 de ter o ditame antes de que remate o mes de maio\u201d, polo que demandou \u00e1 oposici\u00f3n que \u201cse deixee de tacticismos pol\u00edticos e busque un consenso de pa\u00eds\u201d.<\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>Jos\u00e9 Gonz\u00e1lez, que formar\u00e1 parte desta ponencia por parte do Grupo Popular xunto co voceiro de Montes, Jos\u00e9 Silvestre Balseiros, salientou \u201co importante traballo\u201d que se leva feito nesta Comisi\u00f3n de estudo, coa comparecencia de 62 persoas desde o pasado 31 de xaneiro.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>AGRADECEMENTOS<\/strong><\/p>\n<p>Neste sentido, agradeceu o traballo feito por todos os grupos parlamentarios neste tempo, as\u00ed como as aportaci\u00f3ns realizadas por todos estes comparecentes, \u201cque representan os diferentes \u00e1mbitos de co\u00f1ecemento do noso monte, as administraci\u00f3ns p\u00fablicas, os sindicatos ou a Fiscal\u00eda\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>O portavoz popular tam\u00e9n agradeceu \u201co esforzo feito pola Xunta na remisi\u00f3n de m\u00e1is de 30 informes \u00e1 Comisi\u00f3n de estudo\u201d, as\u00ed como de todas as entidades, p\u00fablicas e privadas, que tam\u00e9n fixeron aportaci\u00f3n de documentaci\u00f3n para a elaboraci\u00f3n das conclusi\u00f3ns finais.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cTemos todos os medios para poder facer un ditame \u00e1 altura do que nos demanda a sociedade galega, cunhas recomendaci\u00f3ns para ter un monte multifuncional, vivo, din\u00e1mico e rendible tanto para os seus propietarios como para a sociedade galega\u201d, sinalou.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>COMPROMISO CO PLAN FORESTAL<\/strong><\/p>\n<p>Gonz\u00e1lez fixo un \u201cchamamento aos grupos da oposici\u00f3n para que nos deixemos de tacticismos pol\u00edticos e busquemos un consenso de pa\u00eds, de xeito que as nosas recomendaci\u00f3ns melloren o borrador do Plan Forestal\u201d. Neste sentido, lembrou \u201co compromiso do Presidente da Xunta e da conselleira do Medio Rural de que esas recomendaci\u00f3ns se van ter en conta na redacci\u00f3n definitiva do Plan Forestal\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Cuestionado sobre a limpeza das franxas de protecci\u00f3n, Jos\u00e9 Gonz\u00e1lez afirmou que \u201c\u00e9 algo que esixe a responsabilidade de todos os implicados: os propietarios dos montes, dos concellos e a colaboraci\u00f3n da Xunta, que est\u00e1 a piques de asinar un convenio coa Fegamp para traballar todos xuntos a prol desa limpeza\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santiago, 27 de abril de 2018.- O portavoz do Medio Rural, Jos\u00e9 Gonz\u00e1lez, afirmou hoxe, logo da constituci\u00f3n da ponencia encargada de elaborar o ditame da Comisi\u00f3n de estudo das reformas da pol\u00edtica forestal e de prevenci\u00f3n e extinci\u00f3n de incendios, que \u201ctemos todos os medios para poder facer un ditame \u00e1 altura do que [&hellip;]<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-52747","post","type-post","status-publish","format-standard","hentry","category-pp-de-galicia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Jos\u00e9 Gonz\u00e1lez asegura que \u201ctemos todos os medios para facer un ditame na Comisi\u00f3n sobre a pol\u00edtica forestal \u00e1 altura do que nos demanda a sociedade galega\u201d - PP de Galicia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Jos\u00e9 Gonz\u00e1lez asegura que \u201ctemos todos os medios para facer un ditame na Comisi\u00f3n sobre a pol\u00edtica forestal \u00e1 altura do que nos demanda a sociedade galega\u201d - PP de Galicia\" \/>\n<meta property=\"og:description\" content=\"Santiago, 27 de abril de 2018.- O portavoz do Medio Rural, Jos\u00e9 Gonz\u00e1lez, afirmou hoxe, logo da constituci\u00f3n da ponencia encargada de elaborar o ditame da Comisi\u00f3n de estudo das reformas da pol\u00edtica forestal e de prevenci\u00f3n e extinci\u00f3n de incendios, que \u201ctemos todos os medios para poder facer un ditame \u00e1 altura do que [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/\" \/>\n<meta property=\"og:site_name\" content=\"PP de Galicia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/ppdegalicia\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-27T14:58:01+00:00\" \/>\n<meta name=\"author\" content=\"Super User\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:site\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Super User\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\\\/\"},\"author\":{\"name\":\"Super User\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/d0f013b8388c980665d44009ab762960\"},\"headline\":\"Jos\u00e9 Gonz\u00e1lez asegura que \u201ctemos todos os medios para facer un ditame na Comisi\u00f3n sobre a pol\u00edtica forestal \u00e1 altura do que nos demanda a sociedade galega\u201d\",\"datePublished\":\"2018-04-27T14:58:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\\\/\"},\"wordCount\":444,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"articleSection\":[\"PP de Galicia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\\\/\",\"name\":\"Jos\u00e9 Gonz\u00e1lez asegura que \u201ctemos todos os medios para facer un ditame na Comisi\u00f3n sobre a pol\u00edtica forestal \u00e1 altura do que nos demanda a sociedade galega\u201d - PP de Galicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\"},\"datePublished\":\"2018-04-27T14:58:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jos\u00e9 Gonz\u00e1lez asegura que \u201ctemos todos os medios para facer un ditame na Comisi\u00f3n sobre a pol\u00edtica forestal \u00e1 altura do que nos demanda a sociedade galega\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"name\":\"Partido Popular de Galicia\",\"description\":\"Partido Popular de Galicia\",\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"alternateName\":\"PP de Galicia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\",\"name\":\"Partido Popular de Galicia\",\"alternateName\":\"PP de Galicia\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"contentUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"width\":512,\"height\":512,\"caption\":\"Partido Popular de Galicia\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ppdegalicia\\\/\",\"https:\\\/\\\/x.com\\\/ppdegalicia\",\"https:\\\/\\\/www.tiktok.com\\\/@ppdegalicia\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ppdegalicia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/d0f013b8388c980665d44009ab762960\",\"name\":\"Super User\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"caption\":\"Super User\"},\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/author\\\/ppdegaliciagestion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Jos\u00e9 Gonz\u00e1lez asegura que \u201ctemos todos os medios para facer un ditame na Comisi\u00f3n sobre a pol\u00edtica forestal \u00e1 altura do que nos demanda a sociedade galega\u201d - PP de Galicia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/","og_locale":"es_ES","og_type":"article","og_title":"Jos\u00e9 Gonz\u00e1lez asegura que \u201ctemos todos os medios para facer un ditame na Comisi\u00f3n sobre a pol\u00edtica forestal \u00e1 altura do que nos demanda a sociedade galega\u201d - PP de Galicia","og_description":"Santiago, 27 de abril de 2018.- O portavoz do Medio Rural, Jos\u00e9 Gonz\u00e1lez, afirmou hoxe, logo da constituci\u00f3n da ponencia encargada de elaborar o ditame da Comisi\u00f3n de estudo das reformas da pol\u00edtica forestal e de prevenci\u00f3n e extinci\u00f3n de incendios, que \u201ctemos todos os medios para poder facer un ditame \u00e1 altura do que [&hellip;]","og_url":"https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/","og_site_name":"PP de Galicia","article_publisher":"https:\/\/www.instagram.com\/ppdegalicia\/","article_published_time":"2018-04-27T14:58:01+00:00","author":"Super User","twitter_card":"summary_large_image","twitter_creator":"@ppdegalicia","twitter_site":"@ppdegalicia","twitter_misc":{"Escrito por":"Super User","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/#article","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/"},"author":{"name":"Super User","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/d0f013b8388c980665d44009ab762960"},"headline":"Jos\u00e9 Gonz\u00e1lez asegura que \u201ctemos todos os medios para facer un ditame na Comisi\u00f3n sobre a pol\u00edtica forestal \u00e1 altura do que nos demanda a sociedade galega\u201d","datePublished":"2018-04-27T14:58:01+00:00","mainEntityOfPage":{"@id":"https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/"},"wordCount":444,"commentCount":0,"publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"articleSection":["PP de Galicia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/","url":"https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/","name":"Jos\u00e9 Gonz\u00e1lez asegura que \u201ctemos todos os medios para facer un ditame na Comisi\u00f3n sobre a pol\u00edtica forestal \u00e1 altura do que nos demanda a sociedade galega\u201d - PP de Galicia","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/#website"},"datePublished":"2018-04-27T14:58:01+00:00","breadcrumb":{"@id":"https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ppdegalicia.com\/es\/jose-gonzalez-asegura-que-temos-todos-os-medios-para-facer-un-ditame-na-comision-sobre-a-politica-forestal-a-altura-do-que-nos-demanda-a-sociedade-galega\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ppdegalicia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Jos\u00e9 Gonz\u00e1lez asegura que \u201ctemos todos os medios para facer un ditame na Comisi\u00f3n sobre a pol\u00edtica forestal \u00e1 altura do que nos demanda a sociedade galega\u201d"}]},{"@type":"WebSite","@id":"https:\/\/ppdegalicia.com\/es\/#website","url":"https:\/\/ppdegalicia.com\/es\/","name":"Partido Popular de Galicia","description":"Partido Popular de Galicia","publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"alternateName":"PP de Galicia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ppdegalicia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ppdegalicia.com\/es\/#organization","name":"Partido Popular de Galicia","alternateName":"PP de Galicia","url":"https:\/\/ppdegalicia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","contentUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","width":512,"height":512,"caption":"Partido Popular de Galicia"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ppdegalicia\/","https:\/\/x.com\/ppdegalicia","https:\/\/www.tiktok.com\/@ppdegalicia","https:\/\/www.youtube.com\/user\/ppdegalicia"]},{"@type":"Person","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/d0f013b8388c980665d44009ab762960","name":"Super User","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","caption":"Super User"},"url":"https:\/\/ppdegalicia.com\/es\/author\/ppdegaliciagestion\/"}]}},"_links":{"self":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/52747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/comments?post=52747"}],"version-history":[{"count":0,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/52747\/revisions"}],"wp:attachment":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/media?parent=52747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/categories?post=52747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/tags?post=52747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}