{"id":53891,"date":"2017-12-20T13:19:24","date_gmt":"2017-12-20T11:19:24","guid":{"rendered":"https:\/\/ppdegalicia.com\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/"},"modified":"2017-12-20T13:19:24","modified_gmt":"2017-12-20T11:19:24","slug":"o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia","status":"publish","type":"post","link":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/","title":{"rendered":"O PPdeG apoia instar a Ferroglobe a que potencie o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases en Galicia"},"content":{"rendered":"<p>Santiago, 20 de decembro de 2017.- O Grupo Popular apoiou este m\u00e9rcores no Parlamento unha iniciativa para instar \u00e1 empresa Ferroglobe a que aposte por Galicia para potenciar o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases.<\/p>\n<p><!--more--><\/p>\n<p>&nbsp;<\/p>\n<p>\u201cEstamos nun tempo no que a pol\u00edtica deber\u00eda favorecer a atracci\u00f3n de empresas, non o seu peche\u201d, sinalou o viceportavoz Miguel Tellado. Neste sentido, lembroulle \u00e1 oposici\u00f3n o seu voto en contra \u00e1 Lei de Implantaci\u00f3n de iniciativas empresariais aprobada recentemente no Parlamento, \u201cun texto que serv\u00eda tam\u00e9n para evitar a deslocalizaci\u00f3n\u201d.<\/p>\n<p><strong>&nbsp;<\/strong><\/p>\n<p><strong>DEFENSA DA CORU\u00d1A E COSTA DA MORTE<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>Do mesmo xeito, Tellado sinalou que o PPdeG pensa que \u201cning\u00fan partido da oposici\u00f3n se \u00eda atrever a volver a traer ningunha cuesti\u00f3n relacionada, nin sequera remotamente, con Ferroatl\u00e1ntica\u201d, logo das \u201cmentiras continuadas\u201d que verteron durante meses acerca da solicitude de segregaci\u00f3n das s\u00faas centrais na Costa da Morte.<\/p>\n<p>&nbsp;<\/p>\n<p>As\u00ed, Tellado lembrou que a Xunta foi a primeira en defender \u00e1s comarcas da Coru\u00f1a e da Costa da Morte e aos traballadores de Ferroatl\u00e1ntica tanto en Sab\u00f3n como en Cee-Dumbr\u00eda. Tam\u00e9n puxo en valor que \u201ca Xunta tomase a iniciativa en dar informaci\u00f3n de xeito puntual e veraz \u00e1 opini\u00f3n p\u00fablica, \u00e1 cidadan\u00eda, aos sindicatos e aos alcaldes; as\u00ed coma en dicir que hab\u00eda que respectar<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Santiago, 20 de decembro de 2017.- O Grupo Popular apoiou este m\u00e9rcores no Parlamento unha iniciativa para instar \u00e1 empresa Ferroglobe a que aposte por Galicia para potenciar o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases.<\/p>\n","protected":false},"author":37,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-53891","post","type-post","status-publish","format-standard","hentry","category-pp-de-galicia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O PPdeG apoia instar a Ferroglobe a que potencie o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases en Galicia - PP de Galicia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O PPdeG apoia instar a Ferroglobe a que potencie o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases en Galicia - PP de Galicia\" \/>\n<meta property=\"og:description\" content=\"Santiago, 20 de decembro de 2017.- O Grupo Popular apoiou este m\u00e9rcores no Parlamento unha iniciativa para instar \u00e1 empresa Ferroglobe a que aposte por Galicia para potenciar o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/\" \/>\n<meta property=\"og:site_name\" content=\"PP de Galicia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/ppdegalicia\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-20T11:19:24+00:00\" \/>\n<meta name=\"author\" content=\"Super User\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:site\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Super User\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\\\/\"},\"author\":{\"name\":\"Super User\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/d0f013b8388c980665d44009ab762960\"},\"headline\":\"O PPdeG apoia instar a Ferroglobe a que potencie o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases en Galicia\",\"datePublished\":\"2017-12-20T11:19:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\\\/\"},\"wordCount\":266,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"articleSection\":[\"PP de Galicia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\\\/\",\"name\":\"O PPdeG apoia instar a Ferroglobe a que potencie o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases en Galicia - PP de Galicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\"},\"datePublished\":\"2017-12-20T11:19:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O PPdeG apoia instar a Ferroglobe a que potencie o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases en Galicia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"name\":\"Partido Popular de Galicia\",\"description\":\"Partido Popular de Galicia\",\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"alternateName\":\"PP de Galicia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\",\"name\":\"Partido Popular de Galicia\",\"alternateName\":\"PP de Galicia\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"contentUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"width\":512,\"height\":512,\"caption\":\"Partido Popular de Galicia\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ppdegalicia\\\/\",\"https:\\\/\\\/x.com\\\/ppdegalicia\",\"https:\\\/\\\/www.tiktok.com\\\/@ppdegalicia\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ppdegalicia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/d0f013b8388c980665d44009ab762960\",\"name\":\"Super User\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g\",\"caption\":\"Super User\"},\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/author\\\/ppdegaliciagestion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O PPdeG apoia instar a Ferroglobe a que potencie o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases en Galicia - PP de Galicia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/","og_locale":"es_ES","og_type":"article","og_title":"O PPdeG apoia instar a Ferroglobe a que potencie o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases en Galicia - PP de Galicia","og_description":"Santiago, 20 de decembro de 2017.- O Grupo Popular apoiou este m\u00e9rcores no Parlamento unha iniciativa para instar \u00e1 empresa Ferroglobe a que aposte por Galicia para potenciar o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases.","og_url":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/","og_site_name":"PP de Galicia","article_publisher":"https:\/\/www.instagram.com\/ppdegalicia\/","article_published_time":"2017-12-20T11:19:24+00:00","author":"Super User","twitter_card":"summary_large_image","twitter_creator":"@ppdegalicia","twitter_site":"@ppdegalicia","twitter_misc":{"Escrito por":"Super User","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/#article","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/"},"author":{"name":"Super User","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/d0f013b8388c980665d44009ab762960"},"headline":"O PPdeG apoia instar a Ferroglobe a que potencie o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases en Galicia","datePublished":"2017-12-20T11:19:24+00:00","mainEntityOfPage":{"@id":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/"},"wordCount":266,"commentCount":0,"publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"articleSection":["PP de Galicia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/","url":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/","name":"O PPdeG apoia instar a Ferroglobe a que potencie o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases en Galicia - PP de Galicia","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/#website"},"datePublished":"2017-12-20T11:19:24+00:00","breadcrumb":{"@id":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/ppdegalicia.com\/es\/o-ppdeg-apoia-instar-a-ferroglobe-a-que-potencie-o-ciclo-de-producion-de-silicio-solar-en-todas-as-suas-fases-en-galicia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ppdegalicia.com\/es\/"},{"@type":"ListItem","position":2,"name":"O PPdeG apoia instar a Ferroglobe a que potencie o ciclo de produci\u00f3n de silicio solar en todas as s\u00faas fases en Galicia"}]},{"@type":"WebSite","@id":"https:\/\/ppdegalicia.com\/es\/#website","url":"https:\/\/ppdegalicia.com\/es\/","name":"Partido Popular de Galicia","description":"Partido Popular de Galicia","publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"alternateName":"PP de Galicia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ppdegalicia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ppdegalicia.com\/es\/#organization","name":"Partido Popular de Galicia","alternateName":"PP de Galicia","url":"https:\/\/ppdegalicia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","contentUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","width":512,"height":512,"caption":"Partido Popular de Galicia"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ppdegalicia\/","https:\/\/x.com\/ppdegalicia","https:\/\/www.tiktok.com\/@ppdegalicia","https:\/\/www.youtube.com\/user\/ppdegalicia"]},{"@type":"Person","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/d0f013b8388c980665d44009ab762960","name":"Super User","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1db852625ef4948f58d2739bfbc51e4b9bd5c93b8fa340b59fdb594ca0845645?s=96&d=mm&r=g","caption":"Super User"},"url":"https:\/\/ppdegalicia.com\/es\/author\/ppdegaliciagestion\/"}]}},"_links":{"self":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/53891","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/users\/37"}],"replies":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/comments?post=53891"}],"version-history":[{"count":0,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/53891\/revisions"}],"wp:attachment":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/media?parent=53891"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/categories?post=53891"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/tags?post=53891"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}