{"id":56202,"date":"2021-09-21T09:45:41","date_gmt":"2021-09-21T07:45:41","guid":{"rendered":"https:\/\/ppdegalicia.com\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/"},"modified":"2021-09-21T09:45:41","modified_gmt":"2021-09-21T07:45:41","slug":"adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular","status":"publish","type":"post","link":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/","title":{"rendered":"Adri\u00e1n Pardo, Bego\u00f1a Freire, Rosal\u00eda L\u00f3pez, Jes\u00fas Miguel Prado, Mois\u00e9s Rodr\u00edguez, Bel\u00e9n Cachafeiro e Carlos G\u00f3mez ser\u00e1n os novos deputados do Grupo Popular"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-56201\" src=\"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2021\/09\/138cde2035440fb343bbe90ed6848cd4.jpg\" alt=\"\" width=\"1400\" height=\"630\" srcset=\"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2021\/09\/138cde2035440fb343bbe90ed6848cd4.jpg 1400w, https:\/\/ppdegalicia.com\/wp-content\/uploads\/2021\/09\/138cde2035440fb343bbe90ed6848cd4-300x135.jpg 300w, https:\/\/ppdegalicia.com\/wp-content\/uploads\/2021\/09\/138cde2035440fb343bbe90ed6848cd4-1024x461.jpg 1024w, https:\/\/ppdegalicia.com\/wp-content\/uploads\/2021\/09\/138cde2035440fb343bbe90ed6848cd4-768x346.jpg 768w\" sizes=\"(max-width: 1400px) 100vw, 1400px\" \/><\/p>\n<p style=\"text-align: justify;\">Substituir\u00e1n aos sete conselleiros que xa formalizaron a s\u00faa renuncia ao escano a pasada semana<\/p>\n<p><!--more--><\/p>\n<p style=\"text-align: justify;\">Adri\u00e1n Pardo L\u00f3pez, Bego\u00f1a Freire V\u00e1zquez, Rosal\u00eda L\u00f3pez S\u00e1nchez e Jes\u00fas Miguel Prado Pati\u00f1o, pola provincia de A Coru\u00f1a; Mois\u00e9s Rodr\u00edguez P\u00e9rez e Bel\u00e9n Cachafeiro Anta, por Pontevedra; e Carlos G\u00f3mez Salgado, por Ourense, ser\u00e1n os novos deputados do Grupo Popular en substituci\u00f3n dos sete conselleiros que renunciaron \u00e1 s\u00faa acta no Parlamento galego. Respecto do proxecto de Lei de mellora da xesti\u00f3n do ciclo integral da auga, o portavoz popular, Pedro Puy, asegurou esta nova norma \u201cestablecer\u00e1 o mecanismo polo que a Xunta vai seguir apoiando aos concellos que voluntariamente se integren neste novo sistema de xesti\u00f3n\u201d e asegurou que supor\u00e1 \u201cunha redistribuci\u00f3n dos tributos que non implicar\u00e1 un encarecemento da auga\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Pedro Puy comezou a s\u00faa comparecencia felicitando aos novos presidentes provinciais do Partido Popular en Pontevedra e Lugo, Alfonso Rueda e Elena Candia, respectivamente, que foron elixidos esta fin de semana. Puy afirmou que estes congresos provinciais \u201cderon unha imaxe da uni\u00f3n que existe no PPdeG e de que o partido est\u00e1 preparado para levar adiante aquelas iniciativas que nos permitan avanzar na recuperaci\u00f3n econ\u00f3mica e social\u201d. \u201cEste dato contrib\u00fae a confirmar que o PPdeG \u00e9 garant\u00eda de estabilidade pol\u00edtica e de que, nun momento dif\u00edcil como o actual, hai un partido que traballa unido para afrontar os problemas da sociedade galega e non est\u00e1 distra\u00eddo con cuesti\u00f3ns org\u00e1nicas internas\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong><u>POTENCIAR O GOBERNO GALEGO E O GRUPO PARLAMENTARIO<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Por outra banda, o portavoz popular informou da incorporaci\u00f3n de sete novos deputados ao grupo parlamentario e agradeceu \u201co traballo e a participaci\u00f3n dos sete conselleiros que renunciaron \u00e1 s\u00faa acta no Grupo Popular, colaboraci\u00f3n que van seguir tendo co grupo\u201d. \u201cEsta decisi\u00f3n non s\u00f3 vai potenciar ao Goberno galego, sen\u00f3n tam\u00e9n ao propio grupo parlamentario, dado que se incorporan sete persoas con experiencia pol\u00edtica tanto a nivel local como auton\u00f3mico\u201d, engadiu.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">En concreto, os escanos dos conselleiros \u00c1nxeles V\u00e1zquez, Ethel V\u00e1zquez, Fabiola Garc\u00eda e Rosa Quintana ser\u00e1n ocupados por Adri\u00e1n Pardo, Bego\u00f1a Freire, Rosal\u00eda L\u00f3pez e Jes\u00fas Miguel Prado. As\u00ed mesmo, Rom\u00e1n Rodr\u00edguez e Valeriano Mart\u00ednez ser\u00e1n substitu\u00eddos por Mois\u00e9s Rodr\u00edguez e Bel\u00e9n Cachafeiro; mentres que Carlos G\u00f3mez ocupar\u00e1 o lugar de Jos\u00e9 Gonz\u00e1lez.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Cuestionado sobre o anteproxecto de Lei de mellora da xesti\u00f3n do ciclo integral da auga, Pedro Puy considerou \u201cnecesario dar un paso adiante\u201d neste campo no que a competencia \u00e9 municipal. Neste sentido, afirmou que \u201csegue habendo moitos n\u00facleos de poboaci\u00f3n que a\u00ednda non te\u00f1en subministro de auga potable nin sistemas de saneamento\u201d, un problema que \u201cconforme avanza\u00a0 o tempo non \u00e9 s\u00f3 de benestar das familias, sen\u00f3n que tam\u00e9n ten incidencia no territorio, no medioambiente e na econom\u00eda, ademais de na sa\u00fade de todos\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong><u>DIALOGO COA NOVA LEI DE XESTI\u00d3N DA AUGA<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">A trav\u00e9s desta nova Lei establecerase o mecanismo polo que a Xunta seguir\u00e1 apoiando aos concellos que voluntariamente se integren nese novo sistema de xesti\u00f3n, realizando unha reorganizaci\u00f3n dos tributos sen que implique un encarecemento da auga para os cidad\u00e1ns.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">O portavoz popular lembrou que esta nova lei at\u00f3pase en fase de anteproxecto, polo que esta situaci\u00f3n \u201cvai permitir que haxa di\u00e1logo\u201d na s\u00faa tramitaci\u00f3n \u201cpensando no ben com\u00fan e na incidencia social e territorial que ten unha boa xesti\u00f3n do ciclo da auga\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\"><strong><u>OBXECTIVIDADE E NON DISCRECIONALIDADE<\/u><\/strong><\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">As\u00ed mesmo, sobre o reparto dos fondos europeos, Puy considerou \u201cunha m\u00e1goa que non se distribu\u00edsen cun criterio que, polo menos, gozase da presunci\u00f3n da obxectividade, non da discrecionalidade\u201d como optou o Goberno central. \u201cO PSOE perdeu unha gran oportunidade de prestixiar a Uni\u00f3n Europea e de que o pa\u00eds actuase de forma conxunta e sen presunci\u00f3ns de discrecionalidade\u201d, manifestou.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Pedro Puy indicou que a Xunta \u201cfixo un gran esforzo tanto por presentar distintos proxectos como por auspiciar que o sector privado tam\u00e9n presentara candidaturas, a pesar do marco de incerteza\u201d que existe arredor dos fondos europeos. Por\u00e9n, sinalou que logo da entrevista da ministra de Econom\u00eda co Presidente da Xunta o pasado venres \u201cagora hai certas indicaci\u00f3ns de que se faga unha priorizaci\u00f3n\u201d, pero lamentou que \u201co PSOE de Galicia non est\u00e1 a ter ningunha palabra de apoio e seguen nesta versi\u00f3n cr\u00edtica cunha Xunta que est\u00e1 intentando conseguir que Galicia te\u00f1a un trato xusto e obxectivo\u201d por parte do Goberno central<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Substituir\u00e1n aos sete conselleiros que xa formalizaron a s\u00faa renuncia ao escano a pasada semana<\/p>\n","protected":false},"author":38,"featured_media":56201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-56202","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pp-de-galicia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adri\u00e1n Pardo, Bego\u00f1a Freire, Rosal\u00eda L\u00f3pez, Jes\u00fas Miguel Prado, Mois\u00e9s Rodr\u00edguez, Bel\u00e9n Cachafeiro e Carlos G\u00f3mez ser\u00e1n os novos deputados do Grupo Popular - PP de Galicia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adri\u00e1n Pardo, Bego\u00f1a Freire, Rosal\u00eda L\u00f3pez, Jes\u00fas Miguel Prado, Mois\u00e9s Rodr\u00edguez, Bel\u00e9n Cachafeiro e Carlos G\u00f3mez ser\u00e1n os novos deputados do Grupo Popular - PP de Galicia\" \/>\n<meta property=\"og:description\" content=\"Substituir\u00e1n aos sete conselleiros que xa formalizaron a s\u00faa renuncia ao escano a pasada semana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/\" \/>\n<meta property=\"og:site_name\" content=\"PP de Galicia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/ppdegalicia\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-21T07:45:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2021\/09\/138cde2035440fb343bbe90ed6848cd4.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1400\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ppdegaliciaredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:site\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ppdegaliciaredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/\"},\"author\":{\"name\":\"ppdegaliciaredes\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/5b822c6f59e872ebdd1142f307dbcb59\"},\"headline\":\"Adri\u00e1n Pardo, Bego\u00f1a Freire, Rosal\u00eda L\u00f3pez, Jes\u00fas Miguel Prado, Mois\u00e9s Rodr\u00edguez, Bel\u00e9n Cachafeiro e Carlos G\u00f3mez ser\u00e1n os novos deputados do Grupo Popular\",\"datePublished\":\"2021-09-21T07:45:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/\"},\"wordCount\":840,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/138cde2035440fb343bbe90ed6848cd4.jpg\",\"articleSection\":[\"PP de Galicia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/\",\"name\":\"Adri\u00e1n Pardo, Bego\u00f1a Freire, Rosal\u00eda L\u00f3pez, Jes\u00fas Miguel Prado, Mois\u00e9s Rodr\u00edguez, Bel\u00e9n Cachafeiro e Carlos G\u00f3mez ser\u00e1n os novos deputados do Grupo Popular - PP de Galicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/138cde2035440fb343bbe90ed6848cd4.jpg\",\"datePublished\":\"2021-09-21T07:45:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/138cde2035440fb343bbe90ed6848cd4.jpg\",\"contentUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/138cde2035440fb343bbe90ed6848cd4.jpg\",\"width\":1400,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adri\u00e1n Pardo, Bego\u00f1a Freire, Rosal\u00eda L\u00f3pez, Jes\u00fas Miguel Prado, Mois\u00e9s Rodr\u00edguez, Bel\u00e9n Cachafeiro e Carlos G\u00f3mez ser\u00e1n os novos deputados do Grupo Popular\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"name\":\"Partido Popular de Galicia\",\"description\":\"Partido Popular de Galicia\",\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"alternateName\":\"PP de Galicia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\",\"name\":\"Partido Popular de Galicia\",\"alternateName\":\"PP de Galicia\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"contentUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"width\":512,\"height\":512,\"caption\":\"Partido Popular de Galicia\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ppdegalicia\\\/\",\"https:\\\/\\\/x.com\\\/ppdegalicia\",\"https:\\\/\\\/www.tiktok.com\\\/@ppdegalicia\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ppdegalicia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/5b822c6f59e872ebdd1142f307dbcb59\",\"name\":\"ppdegaliciaredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g\",\"caption\":\"ppdegaliciaredes\"},\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/author\\\/ppdegaliciaredes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adri\u00e1n Pardo, Bego\u00f1a Freire, Rosal\u00eda L\u00f3pez, Jes\u00fas Miguel Prado, Mois\u00e9s Rodr\u00edguez, Bel\u00e9n Cachafeiro e Carlos G\u00f3mez ser\u00e1n os novos deputados do Grupo Popular - PP de Galicia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/","og_locale":"es_ES","og_type":"article","og_title":"Adri\u00e1n Pardo, Bego\u00f1a Freire, Rosal\u00eda L\u00f3pez, Jes\u00fas Miguel Prado, Mois\u00e9s Rodr\u00edguez, Bel\u00e9n Cachafeiro e Carlos G\u00f3mez ser\u00e1n os novos deputados do Grupo Popular - PP de Galicia","og_description":"Substituir\u00e1n aos sete conselleiros que xa formalizaron a s\u00faa renuncia ao escano a pasada semana","og_url":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/","og_site_name":"PP de Galicia","article_publisher":"https:\/\/www.instagram.com\/ppdegalicia\/","article_published_time":"2021-09-21T07:45:41+00:00","og_image":[{"width":1400,"height":630,"url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2021\/09\/138cde2035440fb343bbe90ed6848cd4.jpg","type":"image\/jpeg"}],"author":"ppdegaliciaredes","twitter_card":"summary_large_image","twitter_creator":"@ppdegalicia","twitter_site":"@ppdegalicia","twitter_misc":{"Escrito por":"ppdegaliciaredes","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/#article","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/"},"author":{"name":"ppdegaliciaredes","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/5b822c6f59e872ebdd1142f307dbcb59"},"headline":"Adri\u00e1n Pardo, Bego\u00f1a Freire, Rosal\u00eda L\u00f3pez, Jes\u00fas Miguel Prado, Mois\u00e9s Rodr\u00edguez, Bel\u00e9n Cachafeiro e Carlos G\u00f3mez ser\u00e1n os novos deputados do Grupo Popular","datePublished":"2021-09-21T07:45:41+00:00","mainEntityOfPage":{"@id":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/"},"wordCount":840,"commentCount":0,"publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/#primaryimage"},"thumbnailUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2021\/09\/138cde2035440fb343bbe90ed6848cd4.jpg","articleSection":["PP de Galicia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/","url":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/","name":"Adri\u00e1n Pardo, Bego\u00f1a Freire, Rosal\u00eda L\u00f3pez, Jes\u00fas Miguel Prado, Mois\u00e9s Rodr\u00edguez, Bel\u00e9n Cachafeiro e Carlos G\u00f3mez ser\u00e1n os novos deputados do Grupo Popular - PP de Galicia","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/#primaryimage"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/#primaryimage"},"thumbnailUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2021\/09\/138cde2035440fb343bbe90ed6848cd4.jpg","datePublished":"2021-09-21T07:45:41+00:00","breadcrumb":{"@id":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/#primaryimage","url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2021\/09\/138cde2035440fb343bbe90ed6848cd4.jpg","contentUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2021\/09\/138cde2035440fb343bbe90ed6848cd4.jpg","width":1400,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/ppdegalicia.com\/es\/adrian-pardo-begona-freire-rosalia-lopez-jesus-miguel-prado-moises-rodriguez-belen-cachafeiro-e-carlos-gomez-seran-os-novos-deputados-do-grupo-popular\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ppdegalicia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Adri\u00e1n Pardo, Bego\u00f1a Freire, Rosal\u00eda L\u00f3pez, Jes\u00fas Miguel Prado, Mois\u00e9s Rodr\u00edguez, Bel\u00e9n Cachafeiro e Carlos G\u00f3mez ser\u00e1n os novos deputados do Grupo Popular"}]},{"@type":"WebSite","@id":"https:\/\/ppdegalicia.com\/es\/#website","url":"https:\/\/ppdegalicia.com\/es\/","name":"Partido Popular de Galicia","description":"Partido Popular de Galicia","publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"alternateName":"PP de Galicia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ppdegalicia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ppdegalicia.com\/es\/#organization","name":"Partido Popular de Galicia","alternateName":"PP de Galicia","url":"https:\/\/ppdegalicia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","contentUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","width":512,"height":512,"caption":"Partido Popular de Galicia"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ppdegalicia\/","https:\/\/x.com\/ppdegalicia","https:\/\/www.tiktok.com\/@ppdegalicia","https:\/\/www.youtube.com\/user\/ppdegalicia"]},{"@type":"Person","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/5b822c6f59e872ebdd1142f307dbcb59","name":"ppdegaliciaredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g","caption":"ppdegaliciaredes"},"url":"https:\/\/ppdegalicia.com\/es\/author\/ppdegaliciaredes\/"}]}},"_links":{"self":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/56202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/comments?post=56202"}],"version-history":[{"count":0,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/56202\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/media\/56201"}],"wp:attachment":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/media?parent=56202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/categories?post=56202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/tags?post=56202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}