{"id":58117,"date":"2023-04-11T20:00:29","date_gmt":"2023-04-11T18:00:29","guid":{"rendered":"https:\/\/ppdegalicia.com\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/"},"modified":"2023-04-11T20:00:29","modified_gmt":"2023-04-11T18:00:29","slug":"o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste","status":"publish","type":"post","link":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/","title":{"rendered":"O Parlamento galego solicita ao Goberno central unha reuni\u00f3n urxente do comisario do Corredor Atl\u00e1ntico coas comunidades do noroeste"},"content":{"rendered":"<p><img fetchpriority=\"high\" decoding=\"async\" class=\" size-full wp-image-58116\" src=\"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/942ea5c11c1edd51d6097757ba97f0d3.jpg\" alt=\"\" width=\"1776\" height=\"1184\" srcset=\"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/942ea5c11c1edd51d6097757ba97f0d3.jpg 1776w, https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/942ea5c11c1edd51d6097757ba97f0d3-300x200.jpg 300w, https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/942ea5c11c1edd51d6097757ba97f0d3-1024x683.jpg 1024w, https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/942ea5c11c1edd51d6097757ba97f0d3-768x512.jpg 768w, https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/942ea5c11c1edd51d6097757ba97f0d3-1536x1024.jpg 1536w\" sizes=\"(max-width: 1776px) 100vw, 1776px\" \/><\/p>\n<p>11 de abril de 2023. O Parlamento de Galicia aprobou hoxe a proposici\u00f3n non de lei do Grupo Popular a trav\u00e9s da que se solicita ao Goberno de Espa\u00f1a a convocatoria urxente dunha xuntanza do comisario do Corredor Atl\u00e1ntico coas comunidades de Galicia, Asturias e Castela e Le\u00f3n para tratar as necesidades espec\u00edficas desta infraestrutura de comunicaci\u00f3n, para o que se pide un investimento de 8.000 mill\u00f3ns de euros en actuaci\u00f3ns prioritarias.<\/p>\n<p><!--more--><\/p>\n<p>As\u00ed mesmo, solic\u00edtase a inclusi\u00f3n na rede transeuropea ferroviaria de mercador\u00edas (TEN-T) o denominado trazado norte: li\u00f1a Ferrol-A Coru\u00f1a-Betanzos-Lugo-Monforte-Le\u00f3n, coa correspondente dotaci\u00f3n orzamentaria que permita a s\u00faa completa electrificaci\u00f3n.<\/p>\n<p>\u00a0<\/p>\n<p>O portavoz popular de Infraestruturas, Jos\u00e9 Manuel Balseiro, manifestou que \u201ca falta de impulso e de avances no desenvolvemento do Corredor Atl\u00e1ntico \u00e9 hoxe unha evidencia incuestionable que motiva unha gran preocupaci\u00f3n por parte da Xunta e das comunidades do noroeste, preocupaci\u00f3n compartida tam\u00e9n polas organizaci\u00f3ns empresariais\u201d.<\/p>\n<p>\u00a0<\/p>\n<p><strong>NADA SE FIXO DESDE 2019<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>\u201cPracticamente nada se ti\u00f1a movido no Corredor Atl\u00e1ntico noroeste desde que, a comezos de 2019, o Ministerio de Transportes presentara o seu plan\u201d, lamentou Balseiro, quen salientou que \u201cpara rachar esta par\u00e1lise o pasado 27 de xaneiro tivo lugar en Santiago un cumio no que as comunidades do noroeste insistiron na s\u00faa petici\u00f3n de impulsar o corredor\u201d.<\/p>\n<p>\u00a0<\/p>\n<p>Froito desta reuni\u00f3n, e coincidindo coa s\u00faa celebraci\u00f3n, o Goberno de Pedro S\u00e1nchez nomeou un comisario para o Corredor Atl\u00e1ntico, como interlocutor entre as administraci\u00f3ns e as entidades, ao tempo que as comunidades aut\u00f3nomas presentaron unha estratexia conxunta para que o Goberno de Espa\u00f1a elabore o futuro Plan Director, no que se recolla de forma detallada e cun calendario preciso os investimentos e as actuaci\u00f3ns necesarias, cifradas en preto de 8.000 mill\u00f3ns de euros.<\/p>\n<p>\u00a0<\/p>\n<p>\u201cO nomeamento deste comisario serviu para constatar que o Goberno de Espa\u00f1a non iniciou a\u00ednda a elaboraci\u00f3n deste Plan Director do Corredor Atl\u00e1ntico, que non se espera que estea elaborado ata o futuro mes de outubro\u201d, explicou o portavoz popular, quen engadiu que \u201co documento trasladado polo comisionado \u00e1s comunidades incl\u00fae erros, imprecisi\u00f3ns e ausencias notorias, como a sa\u00edda sur de Vigo ou as variantes dos Peares, Canabal, Monforte, Covas e Manzanal.<\/p>\n<p>\u00a0<\/p>\n<p><strong>HORIZONTE TEMPORAL PARA 2040<\/strong><\/p>\n<p>\u00a0<\/p>\n<p>Respecto dos prazos de execuci\u00f3n do Corredor Atl\u00e1ntico, Jos\u00e9 Manuel Balseiro cualificou de \u201cpouco crible a data de 2032 para estar operativo, porque a estratexia coordinada e conxunta elaborada polas comunidades aut\u00f3nomas, identificando obxectivos concretos e actuaci\u00f3ns prioritarias, establece como horizonte temporal o ano 2040\u201d.<\/p>\n<p>\u00a0<\/p>\n<p>\u201cA unidade de acci\u00f3n puxo sobre a mesa a necesidade de que o Goberno de Espa\u00f1a impulse con decisi\u00f3n o Corredor Atl\u00e1ntico, unha infraestrutura clave para que Galicia non quede illada no mapa das infraestruturas continentais\u201d, manifestou o portavoz popular.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>11 de abril de 2023. O Parlamento de Galicia aprobou hoxe a proposici\u00f3n non de lei do Grupo Popular a trav\u00e9s da que se solicita ao Goberno de Espa\u00f1a a convocatoria urxente dunha xuntanza do comisario do Corredor Atl\u00e1ntico coas comunidades de Galicia, Asturias e Castela e Le\u00f3n para tratar as necesidades espec\u00edficas desta infraestrutura [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":58116,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-58117","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pp-de-galicia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O Parlamento galego solicita ao Goberno central unha reuni\u00f3n urxente do comisario do Corredor Atl\u00e1ntico coas comunidades do noroeste - PP de Galicia<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O Parlamento galego solicita ao Goberno central unha reuni\u00f3n urxente do comisario do Corredor Atl\u00e1ntico coas comunidades do noroeste - PP de Galicia\" \/>\n<meta property=\"og:description\" content=\"11 de abril de 2023. O Parlamento de Galicia aprobou hoxe a proposici\u00f3n non de lei do Grupo Popular a trav\u00e9s da que se solicita ao Goberno de Espa\u00f1a a convocatoria urxente dunha xuntanza do comisario do Corredor Atl\u00e1ntico coas comunidades de Galicia, Asturias e Castela e Le\u00f3n para tratar as necesidades espec\u00edficas desta infraestrutura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/\" \/>\n<meta property=\"og:site_name\" content=\"PP de Galicia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/ppdegalicia\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-11T18:00:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/942ea5c11c1edd51d6097757ba97f0d3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1776\" \/>\n\t<meta property=\"og:image:height\" content=\"1184\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ppdegaliciaredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:site\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ppdegaliciaredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/\"},\"author\":{\"name\":\"ppdegaliciaredes\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/5b822c6f59e872ebdd1142f307dbcb59\"},\"headline\":\"O Parlamento galego solicita ao Goberno central unha reuni\u00f3n urxente do comisario do Corredor Atl\u00e1ntico coas comunidades do noroeste\",\"datePublished\":\"2023-04-11T18:00:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/\"},\"wordCount\":508,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/942ea5c11c1edd51d6097757ba97f0d3.jpg\",\"articleSection\":[\"PP de Galicia\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/\",\"name\":\"O Parlamento galego solicita ao Goberno central unha reuni\u00f3n urxente do comisario do Corredor Atl\u00e1ntico coas comunidades do noroeste - PP de Galicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/942ea5c11c1edd51d6097757ba97f0d3.jpg\",\"datePublished\":\"2023-04-11T18:00:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/942ea5c11c1edd51d6097757ba97f0d3.jpg\",\"contentUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/942ea5c11c1edd51d6097757ba97f0d3.jpg\",\"width\":1776,\"height\":1184},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O Parlamento galego solicita ao Goberno central unha reuni\u00f3n urxente do comisario do Corredor Atl\u00e1ntico coas comunidades do noroeste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"name\":\"Partido Popular de Galicia\",\"description\":\"Partido Popular de Galicia\",\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"alternateName\":\"PP de Galicia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\",\"name\":\"Partido Popular de Galicia\",\"alternateName\":\"PP de Galicia\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"contentUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"width\":512,\"height\":512,\"caption\":\"Partido Popular de Galicia\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ppdegalicia\\\/\",\"https:\\\/\\\/x.com\\\/ppdegalicia\",\"https:\\\/\\\/www.tiktok.com\\\/@ppdegalicia\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ppdegalicia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/5b822c6f59e872ebdd1142f307dbcb59\",\"name\":\"ppdegaliciaredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g\",\"caption\":\"ppdegaliciaredes\"},\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/author\\\/ppdegaliciaredes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O Parlamento galego solicita ao Goberno central unha reuni\u00f3n urxente do comisario do Corredor Atl\u00e1ntico coas comunidades do noroeste - PP de Galicia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/","og_locale":"es_ES","og_type":"article","og_title":"O Parlamento galego solicita ao Goberno central unha reuni\u00f3n urxente do comisario do Corredor Atl\u00e1ntico coas comunidades do noroeste - PP de Galicia","og_description":"11 de abril de 2023. O Parlamento de Galicia aprobou hoxe a proposici\u00f3n non de lei do Grupo Popular a trav\u00e9s da que se solicita ao Goberno de Espa\u00f1a a convocatoria urxente dunha xuntanza do comisario do Corredor Atl\u00e1ntico coas comunidades de Galicia, Asturias e Castela e Le\u00f3n para tratar as necesidades espec\u00edficas desta infraestrutura [&hellip;]","og_url":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/","og_site_name":"PP de Galicia","article_publisher":"https:\/\/www.instagram.com\/ppdegalicia\/","article_published_time":"2023-04-11T18:00:29+00:00","og_image":[{"width":1776,"height":1184,"url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/942ea5c11c1edd51d6097757ba97f0d3.jpg","type":"image\/jpeg"}],"author":"ppdegaliciaredes","twitter_card":"summary_large_image","twitter_creator":"@ppdegalicia","twitter_site":"@ppdegalicia","twitter_misc":{"Escrito por":"ppdegaliciaredes","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/#article","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/"},"author":{"name":"ppdegaliciaredes","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/5b822c6f59e872ebdd1142f307dbcb59"},"headline":"O Parlamento galego solicita ao Goberno central unha reuni\u00f3n urxente do comisario do Corredor Atl\u00e1ntico coas comunidades do noroeste","datePublished":"2023-04-11T18:00:29+00:00","mainEntityOfPage":{"@id":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/"},"wordCount":508,"commentCount":0,"publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/#primaryimage"},"thumbnailUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/942ea5c11c1edd51d6097757ba97f0d3.jpg","articleSection":["PP de Galicia"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/","url":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/","name":"O Parlamento galego solicita ao Goberno central unha reuni\u00f3n urxente do comisario do Corredor Atl\u00e1ntico coas comunidades do noroeste - PP de Galicia","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/#primaryimage"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/#primaryimage"},"thumbnailUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/942ea5c11c1edd51d6097757ba97f0d3.jpg","datePublished":"2023-04-11T18:00:29+00:00","breadcrumb":{"@id":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/#primaryimage","url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/942ea5c11c1edd51d6097757ba97f0d3.jpg","contentUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/942ea5c11c1edd51d6097757ba97f0d3.jpg","width":1776,"height":1184},{"@type":"BreadcrumbList","@id":"https:\/\/ppdegalicia.com\/es\/o-parlamento-galego-solicita-ao-goberno-central-unha-reunion-urxente-do-comisario-do-corredor-atlantico-coas-comunidades-do-noroeste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ppdegalicia.com\/es\/"},{"@type":"ListItem","position":2,"name":"O Parlamento galego solicita ao Goberno central unha reuni\u00f3n urxente do comisario do Corredor Atl\u00e1ntico coas comunidades do noroeste"}]},{"@type":"WebSite","@id":"https:\/\/ppdegalicia.com\/es\/#website","url":"https:\/\/ppdegalicia.com\/es\/","name":"Partido Popular de Galicia","description":"Partido Popular de Galicia","publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"alternateName":"PP de Galicia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ppdegalicia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ppdegalicia.com\/es\/#organization","name":"Partido Popular de Galicia","alternateName":"PP de Galicia","url":"https:\/\/ppdegalicia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","contentUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","width":512,"height":512,"caption":"Partido Popular de Galicia"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ppdegalicia\/","https:\/\/x.com\/ppdegalicia","https:\/\/www.tiktok.com\/@ppdegalicia","https:\/\/www.youtube.com\/user\/ppdegalicia"]},{"@type":"Person","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/5b822c6f59e872ebdd1142f307dbcb59","name":"ppdegaliciaredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g","caption":"ppdegaliciaredes"},"url":"https:\/\/ppdegalicia.com\/es\/author\/ppdegaliciaredes\/"}]}},"_links":{"self":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/58117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/comments?post=58117"}],"version-history":[{"count":0,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/58117\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/media\/58116"}],"wp:attachment":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/media?parent=58117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/categories?post=58117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/tags?post=58117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}