{"id":70779,"date":"2026-03-29T09:36:46","date_gmt":"2026-03-29T08:36:46","guid":{"rendered":"https:\/\/ppdegalicia.com\/?p=70779"},"modified":"2026-03-29T09:36:46","modified_gmt":"2026-03-29T08:36:46","slug":"paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan","status":"publish","type":"post","link":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/","title":{"rendered":"Paula Prado esixe ao Goberno de S\u00e1nchez que se \u201cpo\u00f1a do lado do emprego\u201d e act\u00fae \u201cde forma urxente\u201d para frear a crise do Grupo Los\u00e1n"},"content":{"rendered":"<p style=\"font-weight: 400;\">A secretaria xeral do PPdeG, Paula Prado, urxe ao Goberno de S\u00e1nchez e aos seus socios que act\u00faen \u201cde forma urxente para frear a crise que vive o Grupo Los\u00e1n e que pon en perigo 800 postos de traballo -directos e indirectos- en Galicia\u201d. Informa de que representantes galegos do Partido Popular nas diferentes c\u00e1maras est\u00e1n presentando iniciativas para esixirlle ao Ministerio de Econom\u00eda, ao Ministerio de Industria e a SEPI (Sociedade Estatal de Participaci\u00f3ns Industriais) que \u201cse po\u00f1an do lado das familias e do emprego\u201d e que tomen unha decisi\u00f3n para reverter esta situaci\u00f3n.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">As\u00ed o sinalou a n\u00famero dous dos populares galegos nunha xuntanza en Curtis co alcalde da localidade, Javier Ca\u00ednzos; o alcalde de Vilasantar, Fernando P\u00e9rez, e concelleiros doutros municipios como Oza-Cesuras que se est\u00e1n vendo afectados pola crise desta empresa punteira no sector da madeira. Na cita tam\u00e9n estiveron presentes deputados auton\u00f3micos e do Congreso, as\u00ed como senadores que est\u00e1n atendendo as reivindicaci\u00f3ns locais nas diferentes c\u00e1maras.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">\u201cEstamos ante unha situaci\u00f3n moi delicada que o Goberno de Espa\u00f1a non est\u00e1 escoitando\u201d, lamentou Paula Prado, quen esixiu a S\u00e1nchez que te\u00f1a en conta o plan de viabilidade econ\u00f3mica que presentou en Madrid o Grupo Los\u00e1n para \u201cprotexer eses postos de traballo que est\u00e1n en perigo e que son fundamentais para que a xente contin\u00fae vivindo no rural\u201d.<\/p>\n<p style=\"font-weight: 400;\">A secretaria xeral do PPdeG tam\u00e9n lle recordou ao BNG, que se po\u00f1a \u201cdo lado de Galicia\u201d e que deixe de \u201capoiar incondicionalmente a S\u00e1nchez\u201d. \u201cSon moi bravos en Galicia e moi mansos en Madrid\u201d, engadiu Prado, reivindicando actuaci\u00f3ns \u201cxa, fronte ao desgoberno do Goberno central\u201d.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong><u>DEBATE NO SENADO O 16 DE ABRIL<\/u><\/strong><\/p>\n<p style=\"font-weight: 400;\">Neste sentido, Paula Prado afirmou que o PP presentou unha proposici\u00f3n non de lei no Congreso e no Senado. Concretamente, a do Senado debaterase o 16 de abril e \u201cese d\u00eda veremos como se posicionan o PSOE e o BNG, se ao car\u00f3n da industria ou non\u201d, sinalou. \u201cVeremos se est\u00e1n onde te\u00f1en que estar, cos traballadores, Galicia e co emprego no rural\u201d, como fai o Partido Popular.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Os populares solicitan ao Goberno central que se convoque de maneira urxente unha mesa de traballo institucional para coordinar unha soluci\u00f3n integral, exercer as funci\u00f3ns que corresponden \u00e1 SEPI como instrumento do Goberno en empresas estrat\u00e9xicas e impulsar unha coordinaci\u00f3n efectiva entre os ministerios competentes.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Ademais, piden que se reco\u00f1eza e atenda formalmente o acordo un\u00e1nime adoptado polos concellos afectados en Galicia, trasladando resposta institucional as s\u00faas petici\u00f3ns no marco do principio de lealdade e cooperaci\u00f3n entre administraci\u00f3ns.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\"><strong><u>\u201cAO CAR\u00d3N DOS TRABALLADORES E DA INICIATIVA EMPRESARIAL\u201d<\/u><\/strong><\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Pola s\u00faa banda, o rexedor de Curtis, quen est\u00e1 a liderar as reivindicaci\u00f3ns dos concellos galegos afectados, remarca unha vez m\u00e1is \u201ca urxencia dunha resposta r\u00e1pida, firme e sen demora para a reactivaci\u00f3n industrial do Grupo Los\u00e1n, moi necesaria para Curtis, a comarca e toda Galicia\u201d. \u201cEsta reactivaci\u00f3n \u00e9 vital para o sector, para a econom\u00eda e para estes concellos, tan necesitados de emprego e de actividade econ\u00f3mica para que o rural siga vivo\u201d, engadiu.<\/p>\n<p style=\"font-weight: 400;\">\n<p style=\"font-weight: 400;\">Javier Ca\u00ednzos, que pediu que os ministerios e a SEPI act\u00faen, tam\u00e9n aproveitou para po\u00f1er en valor o labor que o PPdeG est\u00e1 a realizar nas diferentes c\u00e1maras e agradeceu o seu compromiso coa veci\u00f1anza e as familias afectadas pola crise desta empresa. \u201cO PP est\u00e1 sempre onde ten que estar: ao car\u00f3n dos traballadores e ao car\u00f3n da iniciativa empresarial\u201d, destacou.<\/p>\n<p style=\"font-weight: 400;\">\n","protected":false},"excerpt":{"rendered":"<p>A secretaria xeral do PPdeG, Paula Prado, urxe ao Goberno de S\u00e1nchez e aos seus socios que act\u00faen \u201cde forma urxente para frear a crise que vive o Grupo Los\u00e1n e que pon en perigo 800 postos de traballo -directos e indirectos- en Galicia\u201d. Informa de que representantes galegos do Partido Popular nas diferentes c\u00e1maras [&hellip;]<\/p>\n","protected":false},"author":38,"featured_media":70780,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-70779","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-pp-de-galicia"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Paula Prado esixe ao Goberno de S\u00e1nchez que se \u201cpo\u00f1a do lado do emprego\u201d e act\u00fae \u201cde forma urxente\u201d para frear a crise do Grupo Los\u00e1n - PP de Galicia<\/title>\n<meta name=\"description\" content=\"A secretaria xeral do PPdeG, Paula Prado, urxe ao Goberno de S\u00e1nchez e aos seus socios que act\u00faen \u201cde forma urxente para frear a crise que vive o Grupo Los\u00e1n e que pon en perigo 800 postos de traballo -directos e indirectos- en Galicia\u201d. Informa de que representantes galegos do Partido Popular nas diferentes c\u00e1maras est\u00e1n presentando iniciativas para esixirlle ao Ministerio de Econom\u00eda, ao Ministerio de Industria e a SEPI (Sociedade Estatal de Participaci\u00f3ns Industriais) que \u201cse po\u00f1an do lado das familias e do emprego\u201d e que tomen unha decisi\u00f3n para reverter esta situaci\u00f3n.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Paula Prado esixe ao Goberno de S\u00e1nchez que se \u201cpo\u00f1a do lado do emprego\u201d e act\u00fae \u201cde forma urxente\u201d para frear a crise do Grupo Los\u00e1n - PP de Galicia\" \/>\n<meta property=\"og:description\" content=\"A secretaria xeral do PPdeG, Paula Prado, urxe ao Goberno de S\u00e1nchez e aos seus socios que act\u00faen \u201cde forma urxente para frear a crise que vive o Grupo Los\u00e1n e que pon en perigo 800 postos de traballo -directos e indirectos- en Galicia\u201d. Informa de que representantes galegos do Partido Popular nas diferentes c\u00e1maras est\u00e1n presentando iniciativas para esixirlle ao Ministerio de Econom\u00eda, ao Ministerio de Industria e a SEPI (Sociedade Estatal de Participaci\u00f3ns Industriais) que \u201cse po\u00f1an do lado das familias e do emprego\u201d e que tomen unha decisi\u00f3n para reverter esta situaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/\" \/>\n<meta property=\"og:site_name\" content=\"PP de Galicia\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.instagram.com\/ppdegalicia\/\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-29T08:36:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2026\/03\/20260329PaulaPradoGrupoLosanCurtis-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"ppdegaliciaredes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:site\" content=\"@ppdegalicia\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ppdegaliciaredes\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\\\/\"},\"author\":{\"name\":\"ppdegaliciaredes\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/5b822c6f59e872ebdd1142f307dbcb59\"},\"headline\":\"Paula Prado esixe ao Goberno de S\u00e1nchez que se \u201cpo\u00f1a do lado do emprego\u201d e act\u00fae \u201cde forma urxente\u201d para frear a crise do Grupo Los\u00e1n\",\"datePublished\":\"2026-03-29T08:36:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\\\/\"},\"wordCount\":654,\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260329PaulaPradoGrupoLosanCurtis-1-scaled.jpg\",\"articleSection\":[\"PP de Galicia\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\\\/\",\"name\":\"Paula Prado esixe ao Goberno de S\u00e1nchez que se \u201cpo\u00f1a do lado do emprego\u201d e act\u00fae \u201cde forma urxente\u201d para frear a crise do Grupo Los\u00e1n - PP de Galicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260329PaulaPradoGrupoLosanCurtis-1-scaled.jpg\",\"datePublished\":\"2026-03-29T08:36:46+00:00\",\"description\":\"A secretaria xeral do PPdeG, Paula Prado, urxe ao Goberno de S\u00e1nchez e aos seus socios que act\u00faen \u201cde forma urxente para frear a crise que vive o Grupo Los\u00e1n e que pon en perigo 800 postos de traballo -directos e indirectos- en Galicia\u201d. Informa de que representantes galegos do Partido Popular nas diferentes c\u00e1maras est\u00e1n presentando iniciativas para esixirlle ao Ministerio de Econom\u00eda, ao Ministerio de Industria e a SEPI (Sociedade Estatal de Participaci\u00f3ns Industriais) que \u201cse po\u00f1an do lado das familias e do emprego\u201d e que tomen unha decisi\u00f3n para reverter esta situaci\u00f3n.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260329PaulaPradoGrupoLosanCurtis-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/20260329PaulaPradoGrupoLosanCurtis-1-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Paula Prado esixe ao Goberno de S\u00e1nchez que se \u201cpo\u00f1a do lado do emprego\u201d e act\u00fae \u201cde forma urxente\u201d para frear a crise do Grupo Los\u00e1n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"name\":\"Partido Popular de Galicia\",\"description\":\"Partido Popular de Galicia\",\"publisher\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\"},\"alternateName\":\"PP de Galicia\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#organization\",\"name\":\"Partido Popular de Galicia\",\"alternateName\":\"PP de Galicia\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"contentUrl\":\"https:\\\/\\\/ppdegalicia.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/logoPP512.png\",\"width\":512,\"height\":512,\"caption\":\"Partido Popular de Galicia\"},\"image\":{\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/ppdegalicia\\\/\",\"https:\\\/\\\/x.com\\\/ppdegalicia\",\"https:\\\/\\\/www.tiktok.com\\\/@ppdegalicia\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/ppdegalicia\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/#\\\/schema\\\/person\\\/5b822c6f59e872ebdd1142f307dbcb59\",\"name\":\"ppdegaliciaredes\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g\",\"caption\":\"ppdegaliciaredes\"},\"url\":\"https:\\\/\\\/ppdegalicia.com\\\/es\\\/author\\\/ppdegaliciaredes\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Paula Prado esixe ao Goberno de S\u00e1nchez que se \u201cpo\u00f1a do lado do emprego\u201d e act\u00fae \u201cde forma urxente\u201d para frear a crise do Grupo Los\u00e1n - PP de Galicia","description":"A secretaria xeral do PPdeG, Paula Prado, urxe ao Goberno de S\u00e1nchez e aos seus socios que act\u00faen \u201cde forma urxente para frear a crise que vive o Grupo Los\u00e1n e que pon en perigo 800 postos de traballo -directos e indirectos- en Galicia\u201d. Informa de que representantes galegos do Partido Popular nas diferentes c\u00e1maras est\u00e1n presentando iniciativas para esixirlle ao Ministerio de Econom\u00eda, ao Ministerio de Industria e a SEPI (Sociedade Estatal de Participaci\u00f3ns Industriais) que \u201cse po\u00f1an do lado das familias e do emprego\u201d e que tomen unha decisi\u00f3n para reverter esta situaci\u00f3n.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/","og_locale":"es_ES","og_type":"article","og_title":"Paula Prado esixe ao Goberno de S\u00e1nchez que se \u201cpo\u00f1a do lado do emprego\u201d e act\u00fae \u201cde forma urxente\u201d para frear a crise do Grupo Los\u00e1n - PP de Galicia","og_description":"A secretaria xeral do PPdeG, Paula Prado, urxe ao Goberno de S\u00e1nchez e aos seus socios que act\u00faen \u201cde forma urxente para frear a crise que vive o Grupo Los\u00e1n e que pon en perigo 800 postos de traballo -directos e indirectos- en Galicia\u201d. Informa de que representantes galegos do Partido Popular nas diferentes c\u00e1maras est\u00e1n presentando iniciativas para esixirlle ao Ministerio de Econom\u00eda, ao Ministerio de Industria e a SEPI (Sociedade Estatal de Participaci\u00f3ns Industriais) que \u201cse po\u00f1an do lado das familias e do emprego\u201d e que tomen unha decisi\u00f3n para reverter esta situaci\u00f3n.","og_url":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/","og_site_name":"PP de Galicia","article_publisher":"https:\/\/www.instagram.com\/ppdegalicia\/","article_published_time":"2026-03-29T08:36:46+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2026\/03\/20260329PaulaPradoGrupoLosanCurtis-1-scaled.jpg","type":"image\/jpeg"}],"author":"ppdegaliciaredes","twitter_card":"summary_large_image","twitter_creator":"@ppdegalicia","twitter_site":"@ppdegalicia","twitter_misc":{"Escrito por":"ppdegaliciaredes","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/#article","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/"},"author":{"name":"ppdegaliciaredes","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/5b822c6f59e872ebdd1142f307dbcb59"},"headline":"Paula Prado esixe ao Goberno de S\u00e1nchez que se \u201cpo\u00f1a do lado do emprego\u201d e act\u00fae \u201cde forma urxente\u201d para frear a crise do Grupo Los\u00e1n","datePublished":"2026-03-29T08:36:46+00:00","mainEntityOfPage":{"@id":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/"},"wordCount":654,"publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/#primaryimage"},"thumbnailUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2026\/03\/20260329PaulaPradoGrupoLosanCurtis-1-scaled.jpg","articleSection":["PP de Galicia"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/","url":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/","name":"Paula Prado esixe ao Goberno de S\u00e1nchez que se \u201cpo\u00f1a do lado do emprego\u201d e act\u00fae \u201cde forma urxente\u201d para frear a crise do Grupo Los\u00e1n - PP de Galicia","isPartOf":{"@id":"https:\/\/ppdegalicia.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/#primaryimage"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/#primaryimage"},"thumbnailUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2026\/03\/20260329PaulaPradoGrupoLosanCurtis-1-scaled.jpg","datePublished":"2026-03-29T08:36:46+00:00","description":"A secretaria xeral do PPdeG, Paula Prado, urxe ao Goberno de S\u00e1nchez e aos seus socios que act\u00faen \u201cde forma urxente para frear a crise que vive o Grupo Los\u00e1n e que pon en perigo 800 postos de traballo -directos e indirectos- en Galicia\u201d. Informa de que representantes galegos do Partido Popular nas diferentes c\u00e1maras est\u00e1n presentando iniciativas para esixirlle ao Ministerio de Econom\u00eda, ao Ministerio de Industria e a SEPI (Sociedade Estatal de Participaci\u00f3ns Industriais) que \u201cse po\u00f1an do lado das familias e do emprego\u201d e que tomen unha decisi\u00f3n para reverter esta situaci\u00f3n.","breadcrumb":{"@id":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/#primaryimage","url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2026\/03\/20260329PaulaPradoGrupoLosanCurtis-1-scaled.jpg","contentUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2026\/03\/20260329PaulaPradoGrupoLosanCurtis-1-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/ppdegalicia.com\/es\/paula-prado-esixe-ao-goberno-de-sanchez-que-se-pona-do-lado-do-emprego-e-actue-de-forma-urxente-para-frear-a-crise-do-grupo-losan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/ppdegalicia.com\/es\/"},{"@type":"ListItem","position":2,"name":"Paula Prado esixe ao Goberno de S\u00e1nchez que se \u201cpo\u00f1a do lado do emprego\u201d e act\u00fae \u201cde forma urxente\u201d para frear a crise do Grupo Los\u00e1n"}]},{"@type":"WebSite","@id":"https:\/\/ppdegalicia.com\/es\/#website","url":"https:\/\/ppdegalicia.com\/es\/","name":"Partido Popular de Galicia","description":"Partido Popular de Galicia","publisher":{"@id":"https:\/\/ppdegalicia.com\/es\/#organization"},"alternateName":"PP de Galicia","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ppdegalicia.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/ppdegalicia.com\/es\/#organization","name":"Partido Popular de Galicia","alternateName":"PP de Galicia","url":"https:\/\/ppdegalicia.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","contentUrl":"https:\/\/ppdegalicia.com\/wp-content\/uploads\/2023\/04\/logoPP512.png","width":512,"height":512,"caption":"Partido Popular de Galicia"},"image":{"@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/ppdegalicia\/","https:\/\/x.com\/ppdegalicia","https:\/\/www.tiktok.com\/@ppdegalicia","https:\/\/www.youtube.com\/user\/ppdegalicia"]},{"@type":"Person","@id":"https:\/\/ppdegalicia.com\/es\/#\/schema\/person\/5b822c6f59e872ebdd1142f307dbcb59","name":"ppdegaliciaredes","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3c9179cf0256d00c72a48d1f25783c58b6842cd56e85ef3a572881c8e28ccd59?s=96&d=mm&r=g","caption":"ppdegaliciaredes"},"url":"https:\/\/ppdegalicia.com\/es\/author\/ppdegaliciaredes\/"}]}},"_links":{"self":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/70779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/users\/38"}],"replies":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/comments?post=70779"}],"version-history":[{"count":1,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/70779\/revisions"}],"predecessor-version":[{"id":70782,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/posts\/70779\/revisions\/70782"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/media\/70780"}],"wp:attachment":[{"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/media?parent=70779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/categories?post=70779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ppdegalicia.com\/es\/wp-json\/wp\/v2\/tags?post=70779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}